{"id":12851,"date":"2020-04-12T15:18:22","date_gmt":"2020-04-12T13:18:22","guid":{"rendered":"https:\/\/www.banneux-nd.be\/?p=12851"},"modified":"2021-04-02T17:16:16","modified_gmt":"2021-04-02T15:16:16","slug":"bonne-fete-de-paques","status":"publish","type":"post","link":"https:\/\/banneux-nd.be\/en\/bonne-fete-de-paques\/","title":{"rendered":"Bonne f\u00eate de P\u00e2ques"},"content":{"rendered":"\n<p><strong><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-12852 size-large\" src=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-1-e1586697326172-1024x622.jpg\" alt=\"\" width=\"758\" height=\"460\" srcset=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-1-e1586697326172-1024x622.jpg 1024w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-1-e1586697326172-300x182.jpg 300w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-1-e1586697326172-768x467.jpg 768w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-1-e1586697326172.jpg 2048w\" sizes=\"(max-width: 758px) 100vw, 758px\" \/><\/strong><\/p>\n<p><strong>\u00ab\u00a0Ach\u00e8ve en nous ton ouvrage, Seigneur\u00a0\u00bb<\/strong><\/p>\n<p>J\u00e9sus vient d\u2019expirer. Alors, Joseph d\u2019Arimathie sort de l\u2019ombre. Il ose aller chez Pilate pour demander le corps de J\u00e9sus. Et Pilate acc\u00e8de \u00e0 sa demande.<\/p>\n<p>\u00ab\u00a0Apr\u00e8s avoir achet\u00e9 un linceul, Joseph descendit J\u00e9sus de la croix, l\u2019enroula dans le linceul. Il le d\u00e9posa dans une tombe qui \u00e9tait creus\u00e9e dans le rocher, et il roula la pierre \u00e0 l\u2019entr\u00e9e du tombeau\u00a0\u00bb (Marc 15, 46).<\/p>\n<p><strong>Une fin en mineur<\/strong><\/p>\n<p>Joseph n\u2019\u00e9tait pas seul. Les femmes qui avaient suivi J\u00e9sus depuis la Galil\u00e9e \u00e9taient rest\u00e9es l\u00e0 au pied de la croix jusqu\u2019au dernier souffle du Seigneur. Comme elles auraient maintenant voulu prendre le temps pour laver son corps tortur\u00e9\u00a0; comme elles auraient voulu l\u2019embaumer d\u2019aromates et de parfums\u2026\u00a0 Mais le temps presse\u00a0: le sabbat approche, et elles veulent observer le repos, selon le commandement (Luc 24, 1).<\/p>\n<p>Oui, comme elles auraient voulu aller jusqu\u2019au bout. A cause de la Loi, leur \u0153uvre de mis\u00e9ricorde doit rester inachev\u00e9e.<\/p>\n<p>Mais ce n\u2019est que partie remise. Le premier jour de la nouvelle semaine, de grand matin, elles seront l\u00e0, fid\u00e8les au poste\u2026 \u00a0<\/p>\n<p>\u00ab\u00a0Qui nous roulera la pierre\u00a0?\u00a0\u00bb se demandent-elles, chemin faisant.<\/p>\n<p>Surprise\u00a0! Quelqu\u2019un les a devanc\u00e9es, la pierre est roul\u00e9e. Et le cadavre qu\u2019elles voulaient embaumer a disparu\u2026 Aurait-on vol\u00e9 le corps du Seigneur\u00a0? Mais chose curieuse\u00a0: le linceul est bel et bien l\u00e0, \u00e0 l\u2019endroit o\u00f9 l\u2019on avait d\u00e9pos\u00e9 le corps. O\u00f9 est-il pass\u00e9\u00a0? Que s\u2019est-il pass\u00e9\u00a0? Qui est-ce qui les a devanc\u00e9es\u00a0?<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-12859 size-large lazyload\" data-src=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-16-e1586695743402-1024x533.jpg\" alt=\"\" width=\"758\" height=\"395\" data-srcset=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-16-e1586695743402-1024x533.jpg 1024w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-16-e1586695743402-300x156.jpg 300w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-16-e1586695743402-768x400.jpg 768w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-16-e1586695743402.jpg 2048w\" data-sizes=\"(max-width: 758px) 100vw, 758px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 758px; --smush-placeholder-aspect-ratio: 758\/395;\" \/><\/p>\n<p><strong>Une parabole majeure<\/strong><\/p>\n<p>Est-ce que J\u00e9sus lui-m\u00eame ne leur avait pas racont\u00e9 la suite de l\u2019histoire, n\u2019avait-il pas soulev\u00e9 depuis longtemps d\u00e9j\u00e0 un coin du voile (du linceul\u00a0?) qui couvre le grand myst\u00e8re du calvaire\u00a0?<\/p>\n<p>\u00ab\u00a0Je vais aller chez mon p\u00e8re,\u00a0\u00bb avait dit un fils dans une c\u00e9l\u00e8bre parabole.<\/p>\n<p>\u00ab\u00a0Je vais aller chez mon P\u00e8re\u2026 Comme il \u00e9tait encore loin, son P\u00e8re l\u2019aper\u00e7ut et fut pris de piti\u00e9. Il courut se jeter \u00e0 son cou et le couvrit de baisers\u2026<\/p>\n<p>Le P\u00e8re dit aux serviteurs\u00a0: Vite, apportez la plus belle robe, et habillez-le\u00a0; mettez-lui l\u2019anneau au doigt et les sandales aux pieds. Amenez l\u2019Agneau pascal, tuez-le\u00a0; mangeons et festoyons, car mon Fils que voici \u00e9tait mort et il est revenu \u00e0 la vie, il \u00e9tait perdu, et il est retrouv\u00e9\u00a0!\u00a0\u00bb<\/p>\n<p>Et ils se mirent \u00e0 festoyer\u00a0!\u00a0\u00bb (Voir Luc 15, 18-24)<\/p>\n<p>\u00a0<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-12866 size-large lazyload\" data-src=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-7-e1586695900476-1024x578.jpg\" alt=\"\" width=\"758\" height=\"428\" data-srcset=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-7-e1586695900476-1024x578.jpg 1024w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-7-e1586695900476-300x169.jpg 300w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-7-e1586695900476-768x434.jpg 768w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-7-e1586695900476.jpg 2048w\" data-sizes=\"(max-width: 758px) 100vw, 758px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 758px; --smush-placeholder-aspect-ratio: 758\/428;\" \/><\/p>\n<p>\u00a0<strong>\u00ab\u00a0N\u2019ayons pas peur de vivre au monde, Dieu nous a devanc\u00e9s\u00a0\u00bb <\/strong><\/p>\n<p>C\u2019est la f\u00eate de P\u00e2ques, et pourtant beaucoup n\u2019ont pas le c\u0153ur en f\u00eate. Je pense \u00e0 toutes ces familles en deuil, toutes ces personnes qui sont emp\u00each\u00e9es d\u2019accompagner leurs bien-aim\u00e9s jusqu\u2019au bout\u00a0; qui n\u2019ont pas le temps de se recueillir devant leurs d\u00e9funts lav\u00e9s, habill\u00e9s et reposant enfin en paix apr\u00e8s une longue agonie\u00a0; qui n\u2019ont pas l\u2019occasion de les entourer d\u2019amour et de pri\u00e8res avant de les d\u00e9poser dans la terre\u00a0; qui n\u2019ont pas la possibilit\u00e9 de se prendre dans les bras pour se consoler les uns les autres\u2026 Toutes ces \u0153uvres de mis\u00e9ricorde restent cruellement inachev\u00e9es.<\/p>\n<p>Mais plus tard, apr\u00e8s la crise, plus tard nous pourrions faire quelque chose\u2026 Non, pas plus tard\u00a0! C\u2019est ici et maintenant que \u00e7a doit se passer\u00a0! Il nous faut une esp\u00e9rance, ici et maintenant\u00a0!<\/p>\n<p>Car toutes nos \u0153uvres resteront toujours inachev\u00e9es. Heureusement, Quelqu\u2019un prend toujours le relais d\u00e8s que nous faisons un acte d\u2019abandon\u00a0: \u00ab\u00a0P\u00e8re, entre tes mains, je remets ma vie\u00a0\u00bb (Luc 23, 46).<\/p>\n<p>\u00ab\u00a0Comme il \u00e9tait encore loin, son P\u00e8re l\u2019aper\u00e7ut et fut pris de piti\u00e9, il courut se jeter \u00e0 son cou et le couvrit de baisers.<\/p>\n<p>Alors l\u2019enfant lui dit\u00a0: \u00ab\u00a0P\u00e8re, j\u2019ai p\u00e9ch\u00e9 contre le ciel et contre toi\u00a0; je ne suis pas digne d\u2019\u00eatre appel\u00e9 ton enfant\u2026\u00a0\u00bb \u00a0Mais le P\u00e8re dit aux serviteurs\u00a0: \u00ab\u00a0Vite, apportez la plus belle robe, et habillez-le\u00a0; mettez-lui l\u2019anneau au doigt et les sandales aux pieds. Amenez le veau gras\u00a0; tuez-le, mangeons et festoyons, car mon enfant que voici \u00e9tait mort et il est revenu \u00e0 la vie, il \u00e9tait perdu et il est retrouv\u00e9\u00a0\u00bb \u00ab\u00a0Tout est achev\u00e9\u00a0!\u00a0\u00bb (Jean 19, 30)<\/p>\n<p><em>\u00ab\u00a0Seigneur, je te remercie pour l\u2019\u0153uvre que tu es en train d\u2019accomplir dans ma vie. Ce que tu as commenc\u00e9 \u00e0 faire n\u2019est pas termin\u00e9. Quand je serai au ciel, au jour de Christ, alors je serai parfait(e)\u00a0! D\u2019ici l\u00e0, je veux continuer \u00e0 te faire confiance et te laisser achever ton \u0153uvre en moi.\u00a0\u00bb (Eric C\u00e9l\u00e9rier) <\/em><\/p>\n<p><em>Oui, nous t\u2019en supplions, \u00ab\u00a0ach\u00e8ve en nous ton ouvrage, Seigneur\u00a0!\u00a0\u00bb <\/em><\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Joyeuses P\u00e2ques\u00a0!<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Abb\u00e9 Leo Palm<\/p>\n\n\n\n<ul class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"2048\" height=\"1536\" data-src=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-4.jpg\" alt=\"\" data-id=\"12874\" data-link=\"https:\/\/banneux-nd.be\/?attachment_id=12874\" class=\"wp-image-12874 lazyload\" data-srcset=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-4.jpg 2048w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-4-300x225.jpg 300w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-4-768x576.jpg 768w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-4-1024x768.jpg 1024w\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2048px; --smush-placeholder-aspect-ratio: 2048\/1536;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"2048\" height=\"1536\" data-src=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-14.jpg\" alt=\"\" data-id=\"12895\" data-link=\"https:\/\/banneux-nd.be\/?attachment_id=12895\" class=\"wp-image-12895 lazyload\" data-srcset=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-14.jpg 2048w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-14-300x225.jpg 300w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-14-768x576.jpg 768w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-14-1024x768.jpg 1024w\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2048px; --smush-placeholder-aspect-ratio: 2048\/1536;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"2048\" height=\"1536\" data-src=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-35.jpg\" alt=\"\" data-id=\"12909\" data-link=\"https:\/\/banneux-nd.be\/?attachment_id=12909\" class=\"wp-image-12909 lazyload\" data-srcset=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-35.jpg 2048w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-35-300x225.jpg 300w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-35-768x576.jpg 768w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-35-1024x768.jpg 1024w\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2048px; --smush-placeholder-aspect-ratio: 2048\/1536;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-12-1024x768.jpg\" alt=\"\" data-id=\"12923\" data-full-url=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-12.jpg\" data-link=\"https:\/\/banneux-nd.be\/?attachment_id=12923\" class=\"wp-image-12923 lazyload\" data-srcset=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-12-1024x768.jpg 1024w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-12-300x225.jpg 300w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-12-768x576.jpg 768w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-12.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-15-1024x768.jpg\" alt=\"\" data-id=\"12930\" data-full-url=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-15.jpg\" data-link=\"https:\/\/banneux-nd.be\/?attachment_id=12930\" class=\"wp-image-12930 lazyload\" data-srcset=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-15-1024x768.jpg 1024w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-15-300x225.jpg 300w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-15-768x576.jpg 768w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-15.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-33-1024x768.jpg\" alt=\"\" data-id=\"12937\" data-full-url=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-33.jpg\" data-link=\"https:\/\/banneux-nd.be\/?attachment_id=12937\" class=\"wp-image-12937 is-layout-flex wp-block-gallery-is-layout-flex lazyload\" data-srcset=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-33-1024x768.jpg 1024w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-33-300x225.jpg 300w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-33-768x576.jpg 768w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-33.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><\/figure><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Ach\u00e8ve en nous ton ouvrage, Seigneur\u00a0\u00bb J\u00e9sus vient d\u2019expirer. Alors, Joseph d\u2019Arimathie sort de l\u2019ombre. Il ose aller chez Pilate pour demander le corps de J\u00e9sus. Et Pilate acc\u00e8de \u00e0 sa demande. \u00ab\u00a0Apr\u00e8s avoir achet\u00e9 un linceul, Joseph descendit J\u00e9sus de la croix, l\u2019enroula dans le linceul. Il le d\u00e9posa dans une tombe qui \u00e9tait creus\u00e9e dans le rocher, et il roula la pierre \u00e0 l\u2019entr\u00e9e du tombeau\u00a0\u00bb (Marc 15, 46). Une fin en mineur Joseph n\u2019\u00e9tait pas seul. Les femmes qui avaient suivi J\u00e9sus depuis la Galil\u00e9e \u00e9taient rest\u00e9es l\u00e0 au pied de la croix jusqu\u2019au dernier souffle du Seigneur. Comme elles auraient maintenant voulu prendre le temps pour laver son corps tortur\u00e9\u00a0; comme elles auraient voulu l\u2019embaumer d\u2019aromates [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":12866,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[98],"tags":[203,204,194],"class_list":["post-12851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-grandes-fetes-liturgiques","tag-fete-de-paques","tag-sanctuaire-banneux","tag-vierge-des-pauvres"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bonne f\u00eate de P\u00e2ques - Banneux Notre-Dame<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/banneux-nd.be\/en\/bonne-fete-de-paques\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bonne f\u00eate de P\u00e2ques - Banneux Notre-Dame\" \/>\n<meta property=\"og:description\" content=\"\u00ab\u00a0Ach\u00e8ve en nous ton ouvrage, Seigneur\u00a0\u00bb J\u00e9sus vient d\u2019expirer. Alors, Joseph d\u2019Arimathie sort de l\u2019ombre. Il ose aller chez Pilate pour demander le corps de J\u00e9sus. Et Pilate acc\u00e8de \u00e0 sa demande. \u00ab\u00a0Apr\u00e8s avoir achet\u00e9 un linceul, Joseph descendit J\u00e9sus de la croix, l\u2019enroula dans le linceul. Il le d\u00e9posa dans une tombe qui \u00e9tait creus\u00e9e dans le rocher, et il roula la pierre \u00e0 l\u2019entr\u00e9e du tombeau\u00a0\u00bb (Marc 15, 46). Une fin en mineur Joseph n\u2019\u00e9tait pas seul. Les femmes qui avaient suivi J\u00e9sus depuis la Galil\u00e9e \u00e9taient rest\u00e9es l\u00e0 au pied de la croix jusqu\u2019au dernier souffle du Seigneur. Comme elles auraient maintenant voulu prendre le temps pour laver son corps tortur\u00e9\u00a0; comme elles auraient voulu l\u2019embaumer d\u2019aromates [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/banneux-nd.be\/en\/bonne-fete-de-paques\/\" \/>\n<meta property=\"og:site_name\" content=\"Banneux Notre-Dame\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NDBanneux\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-12T13:18:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-02T15:16:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-7-e1586695900476.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"5184\" \/>\n\t<meta property=\"og:image:height\" content=\"2928\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fabian Delarbre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabian Delarbre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/bonne-fete-de-paques\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/bonne-fete-de-paques\\\/\"},\"author\":{\"name\":\"Fabian Delarbre\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/#\\\/schema\\\/person\\\/0d1a4402510d5ffa26dcb30a942708b2\"},\"headline\":\"Bonne f\u00eate de P\u00e2ques\",\"datePublished\":\"2020-04-12T13:18:22+00:00\",\"dateModified\":\"2021-04-02T15:16:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/bonne-fete-de-paques\\\/\"},\"wordCount\":829,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/bonne-fete-de-paques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-7-e1586695900476.jpg\",\"keywords\":[\"f\u00eate de P\u00e2ques\",\"Sanctuaire Banneux\",\"Vierge des Pauvres\"],\"articleSection\":[\"Grandes f\u00eates liturgiques\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/banneux-nd.be\\\/en\\\/bonne-fete-de-paques\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/bonne-fete-de-paques\\\/\",\"url\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/bonne-fete-de-paques\\\/\",\"name\":\"Bonne f\u00eate de P\u00e2ques - Banneux Notre-Dame\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/bonne-fete-de-paques\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/bonne-fete-de-paques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-7-e1586695900476.jpg\",\"datePublished\":\"2020-04-12T13:18:22+00:00\",\"dateModified\":\"2021-04-02T15:16:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/#\\\/schema\\\/person\\\/0d1a4402510d5ffa26dcb30a942708b2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/bonne-fete-de-paques\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/banneux-nd.be\\\/en\\\/bonne-fete-de-paques\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/bonne-fete-de-paques\\\/#primaryimage\",\"url\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-7-e1586695900476.jpg\",\"contentUrl\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-7-e1586695900476.jpg\",\"width\":2048,\"height\":1157},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/bonne-fete-de-paques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/welcome-in-banneux\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bonne f\u00eate de P\u00e2ques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/\",\"name\":\"Banneux Notre-Dame\",\"description\":\"Sanctuaire de la Vierge des Pauvres (Belgique)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/#\\\/schema\\\/person\\\/0d1a4402510d5ffa26dcb30a942708b2\",\"name\":\"Fabian Delarbre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g\",\"caption\":\"Fabian Delarbre\"},\"url\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/author\\\/sanctuaire\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bonne f\u00eate de P\u00e2ques - Banneux Notre-Dame","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/banneux-nd.be\/en\/bonne-fete-de-paques\/","og_locale":"en_US","og_type":"article","og_title":"Bonne f\u00eate de P\u00e2ques - Banneux Notre-Dame","og_description":"\u00ab\u00a0Ach\u00e8ve en nous ton ouvrage, Seigneur\u00a0\u00bb J\u00e9sus vient d\u2019expirer. Alors, Joseph d\u2019Arimathie sort de l\u2019ombre. Il ose aller chez Pilate pour demander le corps de J\u00e9sus. Et Pilate acc\u00e8de \u00e0 sa demande. \u00ab\u00a0Apr\u00e8s avoir achet\u00e9 un linceul, Joseph descendit J\u00e9sus de la croix, l\u2019enroula dans le linceul. Il le d\u00e9posa dans une tombe qui \u00e9tait creus\u00e9e dans le rocher, et il roula la pierre \u00e0 l\u2019entr\u00e9e du tombeau\u00a0\u00bb (Marc 15, 46). Une fin en mineur Joseph n\u2019\u00e9tait pas seul. Les femmes qui avaient suivi J\u00e9sus depuis la Galil\u00e9e \u00e9taient rest\u00e9es l\u00e0 au pied de la croix jusqu\u2019au dernier souffle du Seigneur. Comme elles auraient maintenant voulu prendre le temps pour laver son corps tortur\u00e9\u00a0; comme elles auraient voulu l\u2019embaumer d\u2019aromates [&hellip;]","og_url":"https:\/\/banneux-nd.be\/en\/bonne-fete-de-paques\/","og_site_name":"Banneux Notre-Dame","article_publisher":"https:\/\/www.facebook.com\/NDBanneux\/","article_published_time":"2020-04-12T13:18:22+00:00","article_modified_time":"2021-04-02T15:16:16+00:00","og_image":[{"width":5184,"height":2928,"url":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-7-e1586695900476.jpg","type":"image\/jpeg"}],"author":"Fabian Delarbre","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Fabian Delarbre","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/banneux-nd.be\/en\/bonne-fete-de-paques\/#article","isPartOf":{"@id":"https:\/\/banneux-nd.be\/en\/bonne-fete-de-paques\/"},"author":{"name":"Fabian Delarbre","@id":"https:\/\/banneux-nd.be\/en\/#\/schema\/person\/0d1a4402510d5ffa26dcb30a942708b2"},"headline":"Bonne f\u00eate de P\u00e2ques","datePublished":"2020-04-12T13:18:22+00:00","dateModified":"2021-04-02T15:16:16+00:00","mainEntityOfPage":{"@id":"https:\/\/banneux-nd.be\/en\/bonne-fete-de-paques\/"},"wordCount":829,"commentCount":0,"image":{"@id":"https:\/\/banneux-nd.be\/en\/bonne-fete-de-paques\/#primaryimage"},"thumbnailUrl":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-7-e1586695900476.jpg","keywords":["f\u00eate de P\u00e2ques","Sanctuaire Banneux","Vierge des Pauvres"],"articleSection":["Grandes f\u00eates liturgiques"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/banneux-nd.be\/en\/bonne-fete-de-paques\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/banneux-nd.be\/en\/bonne-fete-de-paques\/","url":"https:\/\/banneux-nd.be\/en\/bonne-fete-de-paques\/","name":"Bonne f\u00eate de P\u00e2ques - Banneux Notre-Dame","isPartOf":{"@id":"https:\/\/banneux-nd.be\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/banneux-nd.be\/en\/bonne-fete-de-paques\/#primaryimage"},"image":{"@id":"https:\/\/banneux-nd.be\/en\/bonne-fete-de-paques\/#primaryimage"},"thumbnailUrl":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-7-e1586695900476.jpg","datePublished":"2020-04-12T13:18:22+00:00","dateModified":"2021-04-02T15:16:16+00:00","author":{"@id":"https:\/\/banneux-nd.be\/en\/#\/schema\/person\/0d1a4402510d5ffa26dcb30a942708b2"},"breadcrumb":{"@id":"https:\/\/banneux-nd.be\/en\/bonne-fete-de-paques\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/banneux-nd.be\/en\/bonne-fete-de-paques\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/banneux-nd.be\/en\/bonne-fete-de-paques\/#primaryimage","url":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-7-e1586695900476.jpg","contentUrl":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-7-e1586695900476.jpg","width":2048,"height":1157},{"@type":"BreadcrumbList","@id":"https:\/\/banneux-nd.be\/en\/bonne-fete-de-paques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/banneux-nd.be\/en\/welcome-in-banneux\/"},{"@type":"ListItem","position":2,"name":"Bonne f\u00eate de P\u00e2ques"}]},{"@type":"WebSite","@id":"https:\/\/banneux-nd.be\/en\/#website","url":"https:\/\/banneux-nd.be\/en\/","name":"Banneux Notre-Dame","description":"Sanctuaire de la Vierge des Pauvres (Belgique)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/banneux-nd.be\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/banneux-nd.be\/en\/#\/schema\/person\/0d1a4402510d5ffa26dcb30a942708b2","name":"Fabian Delarbre","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g","caption":"Fabian Delarbre"},"url":"https:\/\/banneux-nd.be\/en\/author\/sanctuaire\/"}]}},"author_meta":{"display_name":"Fabian Delarbre","author_link":"https:\/\/banneux-nd.be\/en\/author\/sanctuaire\/"},"featured_img":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-7-e1586695900476-300x169.jpg","jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/04\/P\u00e2ques-2020-Vigile-et-messe-de-P\u00e2ques-11-et-12-avril-7-e1586695900476.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/banneux-nd.be\/fr\/category\/grandes-fetes-liturgiques\/\" class=\"advgb-post-tax-term\">Grandes f\u00eates liturgiques<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Grandes f\u00eates liturgiques<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/banneux-nd.be\/fr\/category\/grandes-fetes-liturgiques\/\" class=\"advgb-post-tax-term\">f\u00eate de P\u00e2ques<\/a>","<a href=\"https:\/\/banneux-nd.be\/fr\/category\/grandes-fetes-liturgiques\/\" class=\"advgb-post-tax-term\">Sanctuaire Banneux<\/a>","<a href=\"https:\/\/banneux-nd.be\/fr\/category\/grandes-fetes-liturgiques\/\" class=\"advgb-post-tax-term\">Vierge des Pauvres<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">f\u00eate de P\u00e2ques<\/span>","<span class=\"advgb-post-tax-term\">Sanctuaire Banneux<\/span>","<span class=\"advgb-post-tax-term\">Vierge des Pauvres<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Posted 6 years ago","modified":"Updated 5 years ago"},"absolute_dates":{"created":"Posted on 04\/12\/2020","modified":"Updated on 04\/02\/2021"},"absolute_dates_time":{"created":"Posted on 04\/12\/2020 15 h 18 min","modified":"Updated on 04\/02\/2021 17 h 16 min"},"featured_img_caption":"","series_order":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/posts\/12851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/comments?post=12851"}],"version-history":[{"count":4,"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/posts\/12851\/revisions"}],"predecessor-version":[{"id":12953,"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/posts\/12851\/revisions\/12953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/media\/12866"}],"wp:attachment":[{"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/media?parent=12851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/categories?post=12851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/tags?post=12851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}