{"id":15334,"date":"2021-04-24T15:52:17","date_gmt":"2021-04-24T13:52:17","guid":{"rendered":"https:\/\/banneux-nd.be\/?p=15334"},"modified":"2021-04-24T15:52:18","modified_gmt":"2021-04-24T13:52:18","slug":"ce-qui-nest-pas-donne-est-perdu","status":"publish","type":"post","link":"https:\/\/banneux-nd.be\/en\/ce-qui-nest-pas-donne-est-perdu\/","title":{"rendered":"Ce qui n\u2019est pas donn\u00e9 est perdu"},"content":{"rendered":"\n<h3 style=\"text-align: center;\"><strong>Quatri\u00e8me dimanche du temps pascal B<\/strong><\/h3>\n<p><strong>Lectures\u00a0: <\/strong>Ac 4, 8-12\u00a0; 1 Jn 3, 1-2\u00a0; Jn 10, 11-18<\/p>\n<p><strong>Ma vie, nul ne la prend\u00a0!<\/strong><\/p>\n<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-15358 alignleft\" src=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/04\/allegorie-mort-faucheuse.jpg\" alt=\"\" width=\"284\" height=\"308\" srcset=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/04\/allegorie-mort-faucheuse.jpg 330w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/04\/allegorie-mort-faucheuse-277x300.jpg 277w\" sizes=\"(max-width: 284px) 100vw, 284px\" \/>La mort, les hommes l\u2019ont parfois imagin\u00e9e comme \u00ab la grande faucheuse \u00bb : un \u00eatre squelettique v\u00eatu d\u2019une cape noire et munie d\u2019une faux. Elle r\u00f4de sur notre terre \u00e0 la recherche de vies \u00e0 faucher. Et quand vient notre heure, elle vient cueillir un autre troph\u00e9e. Impossible de lui \u00e9chapper. T\u00f4t ou tard, elle se tient \u00e0 notre porte et nous emporte.<\/p>\n<p style=\"text-align: justify;\"><strong>La grande faucheuse\u2026 fauch\u00e9e\u00a0!<\/strong><\/p>\n<p style=\"text-align: justify;\">Cette mort, nous dit le proph\u00e8te Isa\u00efe, Dieu la d\u00e9truira un jour. Oui, le jour viendra o\u00f9 elle conna\u00eetra une d\u00e9faite totale et irr\u00e9versible. Et nous le croyons\u00a0: c\u2019est chose faite depuis le matin de P\u00e2ques. Le Christ a d\u00e9fait et vaincu la mort une fois pour toutes.<\/p>\n<p style=\"text-align: justify;\">Pour ma part, j\u2019aime imaginer la mort qui monte sur le Golgotha le Vendredi Saint vers trois heures de l\u2019apr\u00e8s-midi. Elle vient pour s\u2019emparer de J\u00e9sus. Mais, \u00e9norme surprise\u00a0: elle ne trouve plus rien, il n\u2019y a rien \u00e0 prendre. Car J\u00e9sus a tout donn\u00e9\u00a0: \u00ab\u00a0Ma vie, nul ne la prend, mais c\u2019est moi qui la donne\u00a0!\u00a0\u00bb (Jn 10, 18) Nul ne la prend, et j\u2019ose ajouter\u00a0: m\u00eame pas et surtout pas la mort\u00a0!<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"wp-image-15349 alignright lazyload\" data-src=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/04\/images.jpg\" alt=\"\" width=\"316\" height=\"180\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 316px; --smush-placeholder-aspect-ratio: 316\/180;\" \/>Oui, sa vie, J\u00e9sus la donne. Depuis quelques heures, il n\u2019a fait que \u00e7a. \u00ab\u00a0Voici mon corps, prenez et mangez. Voici mon sang, prenez et buvez,\u00a0\u00bb dit-il \u00e0 la table eucharistique. Au pied de la croix, il voit sa m\u00e8re et pr\u00e8s d\u2019elle le disciple bien-aim\u00e9\u00a0: alors, il les donne l\u2019un \u00e0 l\u2019autre. \u00ab\u00a0Femme, voici ton fils.\u00a0\u00bb \u00ab\u00a0Voici ta m\u00e8re.\u00a0\u00bb Enfin, il ne reste que son souffle\u00a0: \u00ab\u00a0P\u00e8re, entre tes mains, je remets mon esprit,\u00a0\u00bb dit-il en expirant. Et tout est achev\u00e9, tout est accompli.<\/p>\n<p style=\"text-align: justify;\">La mort s\u2019\u00e9tait d\u00e9j\u00e0 frott\u00e9 les mains squelettiques pensant cueillir son plus grand troph\u00e9e, le Fils unique de Dieu. Elle en est pour ses frais et s\u2019en va les mains vides. Oui, J\u00e9sus s\u2019est vid\u00e9, compl\u00e8tement vid\u00e9. Et le coup de lance du soldat romain lib\u00e8re encore le peu de sang et d\u2019eau qui restent pour qu\u2019ils deviennent les sacrements de l\u2019Eglise.<\/p>\n<p style=\"text-align: justify;\"><strong>Il a tout donn\u00e9\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\">Comme une source qui se donne sans compter, comme une source qui ne retient pas la moindre goutte d\u2019eau, J\u00e9sus a tout donn\u00e9.<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0Ma vie, nul ne la prend, mais c\u2019est moi qui la donne.\u00a0\u00bb Et le Seigneur d\u2019ajouter\u00a0: \u00ab\u00a0Mon P\u00e8re m\u2019aime parce que je la donne pour la reprendre ensuite.\u00a0\u00bb (v. 17) La source est s\u00fbre et certaine que l\u2019eau ne lui manquera jamais et jaillira \u00e0 nouveau \u00e0 travers elle. Elle se sait reli\u00e9e \u00e0 une nappe phr\u00e9atique in\u00e9puisable. J\u00e9sus est assur\u00e9 de sa r\u00e9surrection car il conna\u00eet son P\u00e8re, source de vie intarissable.<\/p>\n<p style=\"text-align: justify;\"><strong>Qui est preneur\u00a0? <\/strong><\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0Ma vie, nul ne la prend\u00a0\u00bb\u00a0? J\u00e9sus esp\u00e8re du fond du c\u0153ur que nous soyons \u00ab\u00a0preneurs\u00a0\u00bb de sa vie, \u00e0 l\u2019image du disciple bien-aim\u00e9\u00a0: quand il entend J\u00e9sus lui dire \u00ab\u00a0voici ta M\u00e8re\u00a0\u00bb, il n\u2019h\u00e9site pas un seul instant\u00a0: il la prend chez lui. Et toute la communaut\u00e9 des premiers chr\u00e9tiens a fait de m\u00eame.<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0Voici mon corps, voici mon sang\u00a0\u00bb\u00a0: nous voyons les premiers chr\u00e9tiens assidus \u00e0 la fraction du pain.<\/p>\n<p style=\"text-align: justify;\">Eux qui \u00e9taient morts de peur, \u00ab\u00a0enterr\u00e9s\u00a0\u00bb vivants au c\u00e9nacle, nous les voyons pleins d\u2019assurance et d\u2019audace une fois que le Ressuscit\u00e9 souffle sur eux\u00a0: \u00ab\u00a0Recevez l\u2019Esprit Saint.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Il s\u2019est fait pauvre pour nous enrichir, il s\u2019est vid\u00e9 pour nous remplir de ses bienfaits. \u00ab\u00a0O pauvret\u00e9, source de richesse, J\u00e9sus, donne-nous un c\u0153ur de pauvre\u00a0!\u00a0\u00bb<\/p>\n<p style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Abb\u00e9 Leo Palm<\/p>\n<hr \/>\n<h3 style=\"text-align: center;\"><strong>Pri\u00e8re universelle<\/strong><\/h3>\n<p><em><strong>Le bon pasteur donne sa vie pour ses brebis. Nous pouvons le prier avec une confiance\u00a0totale\u00a0:<\/strong><\/em><\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong>\u00a0\u00a0 Refrain\u00a0: O Christ ressuscit\u00e9, exauce-nous.<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><em>C\u2019est gr\u00e2ce au nom de J\u00e9sus le Nazar\u00e9en, que cet homme se trouve l\u00e0 devant vous, gu\u00e9ri. <\/em>Seigneur ressuscit\u00e9, que tout homme puisse d\u00e9couvrir que tu es le Sauveur\u00a0: qu\u2019en toi, nous sommes gu\u00e9ris et remis debout. Nous t\u2019en prions.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<ul style=\"text-align: justify;\">\n<li><em>Il est grand, l\u2019amour dont le P\u00e8re nous a combl\u00e9s.<\/em> Seigneur ressuscit\u00e9, que chaque baptis\u00e9 s\u2019\u00e9merveille encore de sa dignit\u00e9 d\u2019enfant de Dieu\u00a0: qu\u2019en toi, nous soyons t\u00e9moins de l\u2019esp\u00e9rance qui d\u00e9passe tout ce que nous pouvons imaginer. Nous t\u2019en prions.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<ul style=\"text-align: justify;\">\n<li><em>Le vrai berger donne sa vie pour ses brebis.<\/em> Seigneur ressuscit\u00e9, appelle encore des femmes et des hommes pr\u00eats \u00e0 donner toute leur vie par amour pour toi, pour le monde et pour l\u2019Eglise. Que, forts de ta pr\u00e9sence, ils t\u00e9moignent fid\u00e8lement et sans crainte. Nous t\u2019en prions.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<ul>\n<li style=\"text-align: justify;\"><em>J\u2019ai encore d\u2019autres brebis qui ne sont pas de cette bergerie.<\/em> Seigneur ressuscit\u00e9, nous te confions l\u2019unit\u00e9 et la communion entre tous les chr\u00e9tiens. Qu\u2019en toi, nous t\u00e9moignions d\u2019une humanit\u00e9 appel\u00e9e \u00e0 se r\u00e9concilier et \u00e0 vivre la solidarit\u00e9 et la fraternit\u00e9. Nous t\u2019en prions.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p style=\"text-align: justify;\"><em><strong>Seigneur J\u00e9sus, bon pasteur, nous comptons vraiment pour toi. Remplis-nous de ton amour et de ta fid\u00e9lit\u00e9. Maintenant et dans les si\u00e8cles des si\u00e8cles.<\/strong><\/em><\/p>\n<hr \/>\n<p>\u00a0<\/p>\n<h3 style=\"text-align: center;\"><strong>Le chariot d\u2019or<\/strong><\/h3>\n<p>J\u2019\u00e9tais all\u00e9, mendiant de porte en porte, sur le chemin du village lorsque ton chariot d\u2019or apparut au loin pareil \u00e0 un r\u00eave splendide et j\u2019admirais quel \u00e9tait ce Roi de tous les rois !<br \/>Mes espoirs s\u2019exalt\u00e8rent et je pensais : c\u2019en est fini des mauvais jours, et d\u00e9j\u00e0 je me tenais pr\u00eat dans l\u2019attente d\u2019aum\u00f4nes spontan\u00e9es et de richesses \u00e9parpill\u00e9es partout dans la poussi\u00e8re.<\/p>\n<p>Le chariot s\u2019arr\u00eata l\u00e0 o\u00f9 je me tenais. Ton regard tomba sur moi et tu descendis avec un sourire. Je sentis que la chance de ma vie \u00e9tait enfin venue. Soudain, alors, tu tendis ta main droite et dis :\u00a0 \u00a0 \u00ab Qu\u2019as-tu \u00e0 me donner ? \u00bb<\/p>\n<p>Ah ! quel jeu royal \u00e9tait-ce l\u00e0 de tendre la main au mendiant pour mendier ! J\u2019\u00e9tais confus et demeurai perplexe ; enfin, de ma besace, je tirai lentement un tout petit grain de bl\u00e9 et te le donnai.<\/p>\n<p>Mais combien fut grande ma surprise lorsque, \u00e0 la fin du jour, vidant \u00e0 terre mon sac, je trouvai un tout petit grain d\u2019or parmi le tas de pauvres grains. Je pleurai am\u00e8rement alors et pensai : \u00ab Que n\u2019ai-je eu le c\u0153ur de te donner mon tout ! \u00bb.<\/p>\n<p style=\"text-align: right;\">(R. Tagore)<\/p>\n<hr \/>\n<h3 style=\"text-align: center;\"><strong>Un chant<\/strong><\/h3>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe class=\"youtube-player lazyload\" width=\"758\" height=\"427\" data-src=\"https:\/\/www.youtube.com\/embed\/3HZZyjD9SKw?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=en-US&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-load-mode=\"1\"><\/iframe><\/span><\/p>\n<p><strong>Christ et Seigneur, Berger de vie<\/strong><br \/><strong>Christ et Seigneur, Berger de vie,<\/strong><br \/><strong>O Fils de Dieu ressuscit\u00e9,<\/strong><br \/><strong>Christ et Seigneur, tu nous conduis<\/strong><br \/><strong>Vers le plein jour dans ta clart\u00e9.<\/strong><br \/>1<br \/>Lumi\u00e8re sur mes pas,<br \/>Tes mots sont v\u00e9rit\u00e9 ;<br \/>Parole en qui je crois,<br \/>Tu viens me lib\u00e9rer.<br \/>2<br \/>Lumi\u00e8re au plus cach\u00e9,<br \/>Reflet du Dieu tr\u00e8s-haut,<br \/>Pr\u00e9sence de l\u2019Aim\u00e9,<br \/>Tu donnes un c\u0153ur nouveau.<br \/>3<br \/>Lumi\u00e8re dans la nuit,<br \/>Tu brilles sur nos croix ;<br \/>La force de l\u2019Esprit<br \/>Nous m\u00e8ne vers ta joie.<\/p>\n<p><em>Musique de Michel Vial, Editions Bayard; parole de Claude Bernard.<\/em><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oui, sa vie, J\u00e9sus la donne. Depuis quelques heures, il n\u2019a fait que \u00e7a. \u00ab\u00a0Voici mon corps, prenez et mangez. Voici mon sang, prenez et buvez,\u00a0\u00bb dit-il \u00e0 la table eucharistique. Au pied de la croix, il voit sa m\u00e8re et pr\u00e8s d\u2019elle le disciple bien-aim\u00e9\u00a0: alors, il les donne l\u2019un \u00e0 l\u2019autre. \u00ab\u00a0Femme, voici ton fils.\u00a0\u00bb \u00ab\u00a0Voici ta m\u00e8re.\u00a0\u00bb Enfin, il ne reste que son souffle\u00a0: \u00ab\u00a0P\u00e8re, entre tes mains, je remets mon esprit,\u00a0\u00bb dit-il en expirant. Et tout est achev\u00e9, tout est accompli.<\/p>\n","protected":false},"author":10,"featured_media":15341,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[48,98],"tags":[274,275,276,209],"class_list":["post-15334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-grandes-fetes-liturgiques","tag-4eme-dimanche-de-paques-b","tag-dimanche-des-vocations","tag-dimanche-du-bon-pasteur","tag-sanctuaire-de-banneux"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ce qui n\u2019est pas donn\u00e9 est perdu - Banneux Notre-Dame<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/banneux-nd.be\/en\/ce-qui-nest-pas-donne-est-perdu\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ce qui n\u2019est pas donn\u00e9 est perdu - Banneux Notre-Dame\" \/>\n<meta property=\"og:description\" content=\"Oui, sa vie, J\u00e9sus la donne. Depuis quelques heures, il n\u2019a fait que \u00e7a. \u00ab\u00a0Voici mon corps, prenez et mangez. Voici mon sang, prenez et buvez,\u00a0\u00bb dit-il \u00e0 la table eucharistique. Au pied de la croix, il voit sa m\u00e8re et pr\u00e8s d\u2019elle le disciple bien-aim\u00e9\u00a0: alors, il les donne l\u2019un \u00e0 l\u2019autre. \u00ab\u00a0Femme, voici ton fils.\u00a0\u00bb \u00ab\u00a0Voici ta m\u00e8re.\u00a0\u00bb Enfin, il ne reste que son souffle\u00a0: \u00ab\u00a0P\u00e8re, entre tes mains, je remets mon esprit,\u00a0\u00bb dit-il en expirant. Et tout est achev\u00e9, tout est accompli.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/banneux-nd.be\/en\/ce-qui-nest-pas-donne-est-perdu\/\" \/>\n<meta property=\"og:site_name\" content=\"Banneux Notre-Dame\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NDBanneux\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-24T13:52:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-24T13:52:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/04\/2389347457_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"286\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fabian Delarbre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabian Delarbre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/ce-qui-nest-pas-donne-est-perdu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/ce-qui-nest-pas-donne-est-perdu\\\/\"},\"author\":{\"name\":\"Fabian Delarbre\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/#\\\/schema\\\/person\\\/0d1a4402510d5ffa26dcb30a942708b2\"},\"headline\":\"Ce qui n\u2019est pas donn\u00e9 est perdu\",\"datePublished\":\"2021-04-24T13:52:17+00:00\",\"dateModified\":\"2021-04-24T13:52:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/ce-qui-nest-pas-donne-est-perdu\\\/\"},\"wordCount\":1249,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/ce-qui-nest-pas-donne-est-perdu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/2389347457_1.jpg\",\"keywords\":[\"4\u00e8me dimanche de P\u00e2ques B\",\"Dimanche des vocations\",\"Dimanche du Bon Pasteur\",\"Sanctuaire de Banneux\"],\"articleSection\":[\"A la Une\",\"Grandes f\u00eates liturgiques\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/banneux-nd.be\\\/en\\\/ce-qui-nest-pas-donne-est-perdu\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/ce-qui-nest-pas-donne-est-perdu\\\/\",\"url\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/ce-qui-nest-pas-donne-est-perdu\\\/\",\"name\":\"Ce qui n\u2019est pas donn\u00e9 est perdu - Banneux Notre-Dame\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/ce-qui-nest-pas-donne-est-perdu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/ce-qui-nest-pas-donne-est-perdu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/2389347457_1.jpg\",\"datePublished\":\"2021-04-24T13:52:17+00:00\",\"dateModified\":\"2021-04-24T13:52:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/#\\\/schema\\\/person\\\/0d1a4402510d5ffa26dcb30a942708b2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/ce-qui-nest-pas-donne-est-perdu\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/banneux-nd.be\\\/en\\\/ce-qui-nest-pas-donne-est-perdu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/ce-qui-nest-pas-donne-est-perdu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/2389347457_1.jpg\",\"contentUrl\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/2389347457_1.jpg\",\"width\":286,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/ce-qui-nest-pas-donne-est-perdu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/welcome-in-banneux\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ce qui n\u2019est pas donn\u00e9 est perdu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/\",\"name\":\"Banneux Notre-Dame\",\"description\":\"Sanctuaire de la Vierge des Pauvres (Belgique)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/#\\\/schema\\\/person\\\/0d1a4402510d5ffa26dcb30a942708b2\",\"name\":\"Fabian Delarbre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g\",\"caption\":\"Fabian Delarbre\"},\"url\":\"https:\\\/\\\/banneux-nd.be\\\/en\\\/author\\\/sanctuaire\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ce qui n\u2019est pas donn\u00e9 est perdu - Banneux Notre-Dame","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/banneux-nd.be\/en\/ce-qui-nest-pas-donne-est-perdu\/","og_locale":"en_US","og_type":"article","og_title":"Ce qui n\u2019est pas donn\u00e9 est perdu - Banneux Notre-Dame","og_description":"Oui, sa vie, J\u00e9sus la donne. Depuis quelques heures, il n\u2019a fait que \u00e7a. \u00ab\u00a0Voici mon corps, prenez et mangez. Voici mon sang, prenez et buvez,\u00a0\u00bb dit-il \u00e0 la table eucharistique. Au pied de la croix, il voit sa m\u00e8re et pr\u00e8s d\u2019elle le disciple bien-aim\u00e9\u00a0: alors, il les donne l\u2019un \u00e0 l\u2019autre. \u00ab\u00a0Femme, voici ton fils.\u00a0\u00bb \u00ab\u00a0Voici ta m\u00e8re.\u00a0\u00bb Enfin, il ne reste que son souffle\u00a0: \u00ab\u00a0P\u00e8re, entre tes mains, je remets mon esprit,\u00a0\u00bb dit-il en expirant. Et tout est achev\u00e9, tout est accompli.","og_url":"https:\/\/banneux-nd.be\/en\/ce-qui-nest-pas-donne-est-perdu\/","og_site_name":"Banneux Notre-Dame","article_publisher":"https:\/\/www.facebook.com\/NDBanneux\/","article_published_time":"2021-04-24T13:52:17+00:00","article_modified_time":"2021-04-24T13:52:18+00:00","og_image":[{"width":286,"height":400,"url":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/04\/2389347457_1.jpg","type":"image\/jpeg"}],"author":"Fabian Delarbre","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Fabian Delarbre","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/banneux-nd.be\/en\/ce-qui-nest-pas-donne-est-perdu\/#article","isPartOf":{"@id":"https:\/\/banneux-nd.be\/en\/ce-qui-nest-pas-donne-est-perdu\/"},"author":{"name":"Fabian Delarbre","@id":"https:\/\/banneux-nd.be\/en\/#\/schema\/person\/0d1a4402510d5ffa26dcb30a942708b2"},"headline":"Ce qui n\u2019est pas donn\u00e9 est perdu","datePublished":"2021-04-24T13:52:17+00:00","dateModified":"2021-04-24T13:52:18+00:00","mainEntityOfPage":{"@id":"https:\/\/banneux-nd.be\/en\/ce-qui-nest-pas-donne-est-perdu\/"},"wordCount":1249,"commentCount":0,"image":{"@id":"https:\/\/banneux-nd.be\/en\/ce-qui-nest-pas-donne-est-perdu\/#primaryimage"},"thumbnailUrl":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/04\/2389347457_1.jpg","keywords":["4\u00e8me dimanche de P\u00e2ques B","Dimanche des vocations","Dimanche du Bon Pasteur","Sanctuaire de Banneux"],"articleSection":["A la Une","Grandes f\u00eates liturgiques"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/banneux-nd.be\/en\/ce-qui-nest-pas-donne-est-perdu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/banneux-nd.be\/en\/ce-qui-nest-pas-donne-est-perdu\/","url":"https:\/\/banneux-nd.be\/en\/ce-qui-nest-pas-donne-est-perdu\/","name":"Ce qui n\u2019est pas donn\u00e9 est perdu - Banneux Notre-Dame","isPartOf":{"@id":"https:\/\/banneux-nd.be\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/banneux-nd.be\/en\/ce-qui-nest-pas-donne-est-perdu\/#primaryimage"},"image":{"@id":"https:\/\/banneux-nd.be\/en\/ce-qui-nest-pas-donne-est-perdu\/#primaryimage"},"thumbnailUrl":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/04\/2389347457_1.jpg","datePublished":"2021-04-24T13:52:17+00:00","dateModified":"2021-04-24T13:52:18+00:00","author":{"@id":"https:\/\/banneux-nd.be\/en\/#\/schema\/person\/0d1a4402510d5ffa26dcb30a942708b2"},"breadcrumb":{"@id":"https:\/\/banneux-nd.be\/en\/ce-qui-nest-pas-donne-est-perdu\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/banneux-nd.be\/en\/ce-qui-nest-pas-donne-est-perdu\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/banneux-nd.be\/en\/ce-qui-nest-pas-donne-est-perdu\/#primaryimage","url":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/04\/2389347457_1.jpg","contentUrl":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/04\/2389347457_1.jpg","width":286,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/banneux-nd.be\/en\/ce-qui-nest-pas-donne-est-perdu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/banneux-nd.be\/en\/welcome-in-banneux\/"},{"@type":"ListItem","position":2,"name":"Ce qui n\u2019est pas donn\u00e9 est perdu"}]},{"@type":"WebSite","@id":"https:\/\/banneux-nd.be\/en\/#website","url":"https:\/\/banneux-nd.be\/en\/","name":"Banneux Notre-Dame","description":"Sanctuaire de la Vierge des Pauvres (Belgique)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/banneux-nd.be\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/banneux-nd.be\/en\/#\/schema\/person\/0d1a4402510d5ffa26dcb30a942708b2","name":"Fabian Delarbre","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g","caption":"Fabian Delarbre"},"url":"https:\/\/banneux-nd.be\/en\/author\/sanctuaire\/"}]}},"author_meta":{"display_name":"Fabian Delarbre","author_link":"https:\/\/banneux-nd.be\/en\/author\/sanctuaire\/"},"featured_img":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/04\/2389347457_1-215x300.jpg","jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/04\/2389347457_1.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/banneux-nd.be\/fr\/category\/a-la-une\/\" class=\"advgb-post-tax-term\">A la Une<\/a>","<a href=\"https:\/\/banneux-nd.be\/fr\/category\/grandes-fetes-liturgiques\/\" class=\"advgb-post-tax-term\">Grandes f\u00eates liturgiques<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">A la Une<\/span>","<span class=\"advgb-post-tax-term\">Grandes f\u00eates liturgiques<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/banneux-nd.be\/fr\/category\/grandes-fetes-liturgiques\/\" class=\"advgb-post-tax-term\">4\u00e8me dimanche de P\u00e2ques B<\/a>","<a href=\"https:\/\/banneux-nd.be\/fr\/category\/grandes-fetes-liturgiques\/\" class=\"advgb-post-tax-term\">Dimanche des vocations<\/a>","<a href=\"https:\/\/banneux-nd.be\/fr\/category\/grandes-fetes-liturgiques\/\" class=\"advgb-post-tax-term\">Dimanche du Bon Pasteur<\/a>","<a href=\"https:\/\/banneux-nd.be\/fr\/category\/grandes-fetes-liturgiques\/\" class=\"advgb-post-tax-term\">Sanctuaire de Banneux<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">4\u00e8me dimanche de P\u00e2ques B<\/span>","<span class=\"advgb-post-tax-term\">Dimanche des vocations<\/span>","<span class=\"advgb-post-tax-term\">Dimanche du Bon Pasteur<\/span>","<span class=\"advgb-post-tax-term\">Sanctuaire de Banneux<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Posted 5 years ago","modified":"Updated 5 years ago"},"absolute_dates":{"created":"Posted on 04\/24\/2021","modified":"Updated on 04\/24\/2021"},"absolute_dates_time":{"created":"Posted on 04\/24\/2021 15 h 52 min","modified":"Updated on 04\/24\/2021 15 h 52 min"},"featured_img_caption":"","series_order":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/posts\/15334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/comments?post=15334"}],"version-history":[{"count":10,"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/posts\/15334\/revisions"}],"predecessor-version":[{"id":15365,"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/posts\/15334\/revisions\/15365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/media\/15341"}],"wp:attachment":[{"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/media?parent=15334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/categories?post=15334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/banneux-nd.be\/en\/wp-json\/wp\/v2\/tags?post=15334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}