{"id":19454,"date":"2024-11-07T23:32:07","date_gmt":"2024-11-07T22:32:07","guid":{"rendered":"https:\/\/banneux-nd.be\/?p=19454"},"modified":"2024-11-07T23:32:07","modified_gmt":"2024-11-07T22:32:07","slug":"8eme-journee-mondiale-des-pauvres","status":"publish","type":"post","link":"https:\/\/banneux-nd.be\/es\/8eme-journee-mondiale-des-pauvres\/","title":{"rendered":"8\u00e8me journ\u00e9e mondiale des Pauvres"},"content":{"rendered":"<h2 style=\"text-align: center;\"><strong><em>La pri\u00e8re du pauvre s\u2019\u00e9l\u00e8ve jusqu\u2019\u00e0 Dieu <span style=\"font-size: 12pt;\">(cf. Siracide 21, 5)<\/span><\/em><\/strong><\/h2>\n<p>Nous sommes d\u00e9j\u00e0 \u00e0 la 8<sup>\u00e8me<\/sup> ann\u00e9e de cette merveilleuse initiative du Pape Fran\u00e7ois, et le sanctuaire de Banneux est heureux d\u2019accueillir, depuis lors, la journ\u00e9e mondiale des Pauvres.<\/p>\n<p>En pr\u00e9paration \u00e0 l\u2019Ann\u00e9e Sainte, le pape a voulu que 2024 soit consacr\u00e9 \u00e0 la pri\u00e8re, il a donc choisi le th\u00e8me en fonction\u00a0!\u00a0 <strong><em>La pri\u00e8re du pauvre s\u2019\u00e9l\u00e8ve jusqu\u2019\u00e0 Dieu (cf. Siracide 21, 5)<\/em><\/strong>\u00a0\u00a0 Dans sa lettre le Pape nous invite \u00e0 prier sans rel\u00e2che en toute occasion et pour tout car Dieu est attentif \u00e0 chacun de nous, il est proche de nous.\u00a0 En guise de conclusion il\u00a0 nous dit\u00a0: <strong><em>\u00ab\u00a0Que la Sainte M\u00e8re de Dieu, Marie Tr\u00e8s Sainte, qui en apparaissant \u00e0 Banneux nous a laiss\u00e9 le message \u00e0 ne pas oublier\u00a0: \u00ab\u00a0Je suis la Vierge des Pauvres\u00a0\u00bb, nous soutienne sur ce chemin. \u00c0 elle, que Dieu a regard\u00e9e pour son humble pauvret\u00e9, accomplissant de grandes choses par son ob\u00e9issance, nous confions notre pri\u00e8re, convaincus qu\u2019elle s\u2019\u00e9l\u00e8vera vers le ciel et sera entendue.\u00a0\u00bb<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"wp-image-19462 alignleft lazyload\" data-src=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2024\/11\/IMG-20231119-WA0018-768x1024.jpg\" alt=\"\" width=\"216\" height=\"288\" data-srcset=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2024\/11\/IMG-20231119-WA0018-768x1023.jpg 768w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2024\/11\/IMG-20231119-WA0018-225x300.jpg 225w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2024\/11\/IMG-20231119-WA0018-1153x1536.jpg 1153w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2024\/11\/IMG-20231119-WA0018.jpg 1200w\" data-sizes=\"(max-width: 216px) 100vw, 216px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 216px; --smush-placeholder-aspect-ratio: 216\/288;\" \/>Un \u00e9v\u00e8nement interdioc\u00e9sain des diff\u00e9rents vicariats en lien avec la solidarit\u00e9 de Li\u00e8ge, du Brabant Wallon, de Bruxelles, de Namur et de Tournai ainsi que plusieurs associations participent au Week-end.<\/p>\n<p>Nous accueillerons plus de 300 personnes pr\u00e9caris\u00e9es, pauvres, sans domicile, isol\u00e9s avec des animateurs. \u00a0Quel regard donne-t-on au pauvre que le croise\u00a0?\u00a0 Un regard souvent n\u00e9gatif, inhumain, voir agressif\u00a0?\u00a0 Ou plut\u00f4t un regard souriant, compatissant, r\u00e9confortant accompagn\u00e9 d\u2019un geste de partage\u00a0?<\/p>\n<p>Des moments d\u2019\u00e9coute, de partage et de pri\u00e8re importants seront propos\u00e9s.\u00a0 Des instants de bonheur, d\u2019\u00e9motion et d\u2019esp\u00e9rance sous le regard maternel de la Vierge des Pauvres seront partag\u00e9s.\u00a0 Notre Dame de Banneux est l\u00e0 pour nous soutenir dans les peines, les douleurs et les pauvret\u00e9s\u00a0; pour se r\u00e9jouir de nos joies, de nos rencontres de nos gestes et de nos sourires.\u00a0 Un Week-end en lien direct avec le Message qu\u2019elle est venue d\u00e9poser dans les mains de la petite voyante, Mariette Beco, en 1933.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>Au programme du Week-end\u00a0:<\/u><\/strong><\/p>\n<h3 style=\"text-align: center;\"><strong>Samedi 16 novembre :<\/strong><\/h3>\n<p>14h00 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Accueil \u00e0 l\u2019\u00e9glise de la Vierge des Pauvres.<\/p>\n<p>14h30 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Ateliers divers ax\u00e9s sur la pri\u00e8re\u00a0 (danse, chants, Parole et partage biblique, jeu sur chapelet, fresque, Parole et terre glaise, \u00e9criture po\u00e8me)<\/p>\n<p>18h00 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Veill\u00e9e et procession aux flambeaux.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\"><strong>Dimanche 17 novembre :<\/strong><\/h3>\n<p>9h30 Activit\u00e9s diverses (chapelet, chemin de croix, chemin de lumi\u00e8re, marche \u00e9change, \u00e9coute, ic\u00f4ne, \u2026).<\/p>\n<p>11h15\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Eucharistie anim\u00e9e par la chorale du Poverello pr\u00e9sid\u00e9e par Mgr Jean-Luc Hudsyn, \u00e9v\u00eaque auxiliaire \u00e9m\u00e9rite de l\u2019Archev\u00each\u00e9 de Malines-Bruxelles.<\/p>\n<p>12h30 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Repas Auberge espagnole \u00e0 l\u2019Hospitalit\u00e9<\/p>\n<p>15h00 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Temps de pri\u00e8re, et envoi<\/p>\n<p>Pour ce qui est de l\u2019auberge espagnole, nous attendons de la solidarit\u00e9 des personnes qui nous rejoindrons pour l\u2019occasion.\u00a0 Chacun apporte, nous mettons tout en commun pour vivre l\u2019entraide.\u00a0 Plusieurs buffets seront dress\u00e9s pour que chacun puisse manger.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-large wp-image-19455 lazyload\" data-src=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2024\/11\/affiche-2024-724x1024.jpg\" alt=\"\" width=\"724\" height=\"1024\" data-srcset=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2024\/11\/affiche-2024-724x1024.jpg 724w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2024\/11\/affiche-2024-212x300.jpg 212w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2024\/11\/affiche-2024-768x1086.jpg 768w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2024\/11\/affiche-2024-1086x1536.jpg 1086w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2024\/11\/affiche-2024-scaled.jpg 1448w\" data-sizes=\"(max-width: 724px) 100vw, 724px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 724px; --smush-placeholder-aspect-ratio: 724\/1024;\" \/><\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pri\u00e8re du pauvre s\u2019\u00e9l\u00e8ve jusqu\u2019\u00e0 Dieu (cf. Siracide 21, 5) Nous sommes d\u00e9j\u00e0 \u00e0 la 8\u00e8me ann\u00e9e de cette merveilleuse initiative du Pape Fran\u00e7ois, et le sanctuaire de Banneux est heureux d\u2019accueillir, depuis lors, la journ\u00e9e mondiale des Pauvres. En pr\u00e9paration \u00e0 l\u2019Ann\u00e9e Sainte, le pape a voulu que 2024 soit consacr\u00e9 \u00e0 la pri\u00e8re, il a donc choisi le th\u00e8me en fonction\u00a0!\u00a0 La pri\u00e8re du pauvre s\u2019\u00e9l\u00e8ve jusqu\u2019\u00e0 Dieu (cf. Siracide 21, 5)\u00a0\u00a0 Dans sa lettre le Pape nous invite \u00e0 prier sans rel\u00e2che en toute occasion et pour tout car Dieu est attentif \u00e0 chacun de nous, il est proche de nous.\u00a0 En guise de conclusion il\u00a0 nous dit\u00a0: \u00ab\u00a0Que la Sainte M\u00e8re de Dieu, Marie Tr\u00e8s [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":19455,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[48],"tags":[134,209,194],"class_list":["post-19454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","tag-journee-mondiale-des-pauvres","tag-sanctuaire-de-banneux","tag-vierge-des-pauvres"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>8\u00e8me journ\u00e9e mondiale des Pauvres - Banneux Notre-Dame<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/banneux-nd.be\/es\/8eme-journee-mondiale-des-pauvres\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"8\u00e8me journ\u00e9e mondiale des Pauvres - Banneux Notre-Dame\" \/>\n<meta property=\"og:description\" content=\"La pri\u00e8re du pauvre s\u2019\u00e9l\u00e8ve jusqu\u2019\u00e0 Dieu (cf. Siracide 21, 5) Nous sommes d\u00e9j\u00e0 \u00e0 la 8\u00e8me ann\u00e9e de cette merveilleuse initiative du Pape Fran\u00e7ois, et le sanctuaire de Banneux est heureux d\u2019accueillir, depuis lors, la journ\u00e9e mondiale des Pauvres. En pr\u00e9paration \u00e0 l\u2019Ann\u00e9e Sainte, le pape a voulu que 2024 soit consacr\u00e9 \u00e0 la pri\u00e8re, il a donc choisi le th\u00e8me en fonction\u00a0!\u00a0 La pri\u00e8re du pauvre s\u2019\u00e9l\u00e8ve jusqu\u2019\u00e0 Dieu (cf. Siracide 21, 5)\u00a0\u00a0 Dans sa lettre le Pape nous invite \u00e0 prier sans rel\u00e2che en toute occasion et pour tout car Dieu est attentif \u00e0 chacun de nous, il est proche de nous.\u00a0 En guise de conclusion il\u00a0 nous dit\u00a0: \u00ab\u00a0Que la Sainte M\u00e8re de Dieu, Marie Tr\u00e8s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/banneux-nd.be\/es\/8eme-journee-mondiale-des-pauvres\/\" \/>\n<meta property=\"og:site_name\" content=\"Banneux Notre-Dame\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NDBanneux\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-07T22:32:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2024\/11\/affiche-2024-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1448\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fabian Delarbre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabian Delarbre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/8eme-journee-mondiale-des-pauvres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/8eme-journee-mondiale-des-pauvres\\\/\"},\"author\":{\"name\":\"Fabian Delarbre\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/#\\\/schema\\\/person\\\/0d1a4402510d5ffa26dcb30a942708b2\"},\"headline\":\"8\u00e8me journ\u00e9e mondiale des Pauvres\",\"datePublished\":\"2024-11-07T22:32:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/8eme-journee-mondiale-des-pauvres\\\/\"},\"wordCount\":524,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/8eme-journee-mondiale-des-pauvres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/affiche-2024-scaled.jpg\",\"keywords\":[\"journ\u00e9e mondiale des pauvres\",\"Sanctuaire de Banneux\",\"Vierge des Pauvres\"],\"articleSection\":[\"A la Une\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/banneux-nd.be\\\/es\\\/8eme-journee-mondiale-des-pauvres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/8eme-journee-mondiale-des-pauvres\\\/\",\"url\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/8eme-journee-mondiale-des-pauvres\\\/\",\"name\":\"8\u00e8me journ\u00e9e mondiale des Pauvres - Banneux Notre-Dame\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/8eme-journee-mondiale-des-pauvres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/8eme-journee-mondiale-des-pauvres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/affiche-2024-scaled.jpg\",\"datePublished\":\"2024-11-07T22:32:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/#\\\/schema\\\/person\\\/0d1a4402510d5ffa26dcb30a942708b2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/8eme-journee-mondiale-des-pauvres\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/banneux-nd.be\\\/es\\\/8eme-journee-mondiale-des-pauvres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/8eme-journee-mondiale-des-pauvres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/affiche-2024-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/affiche-2024-scaled.jpg\",\"width\":1448,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/8eme-journee-mondiale-des-pauvres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"8\u00e8me journ\u00e9e mondiale des Pauvres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/\",\"name\":\"Banneux Notre-Dame\",\"description\":\"Sanctuaire de la Vierge des Pauvres (Belgique)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/#\\\/schema\\\/person\\\/0d1a4402510d5ffa26dcb30a942708b2\",\"name\":\"Fabian Delarbre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g\",\"caption\":\"Fabian Delarbre\"},\"url\":\"https:\\\/\\\/banneux-nd.be\\\/es\\\/author\\\/sanctuaire\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"8\u00e8me journ\u00e9e mondiale des Pauvres - Banneux Notre-Dame","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/banneux-nd.be\/es\/8eme-journee-mondiale-des-pauvres\/","og_locale":"es_ES","og_type":"article","og_title":"8\u00e8me journ\u00e9e mondiale des Pauvres - Banneux Notre-Dame","og_description":"La pri\u00e8re du pauvre s\u2019\u00e9l\u00e8ve jusqu\u2019\u00e0 Dieu (cf. Siracide 21, 5) Nous sommes d\u00e9j\u00e0 \u00e0 la 8\u00e8me ann\u00e9e de cette merveilleuse initiative du Pape Fran\u00e7ois, et le sanctuaire de Banneux est heureux d\u2019accueillir, depuis lors, la journ\u00e9e mondiale des Pauvres. En pr\u00e9paration \u00e0 l\u2019Ann\u00e9e Sainte, le pape a voulu que 2024 soit consacr\u00e9 \u00e0 la pri\u00e8re, il a donc choisi le th\u00e8me en fonction\u00a0!\u00a0 La pri\u00e8re du pauvre s\u2019\u00e9l\u00e8ve jusqu\u2019\u00e0 Dieu (cf. Siracide 21, 5)\u00a0\u00a0 Dans sa lettre le Pape nous invite \u00e0 prier sans rel\u00e2che en toute occasion et pour tout car Dieu est attentif \u00e0 chacun de nous, il est proche de nous.\u00a0 En guise de conclusion il\u00a0 nous dit\u00a0: \u00ab\u00a0Que la Sainte M\u00e8re de Dieu, Marie Tr\u00e8s [&hellip;]","og_url":"https:\/\/banneux-nd.be\/es\/8eme-journee-mondiale-des-pauvres\/","og_site_name":"Banneux Notre-Dame","article_publisher":"https:\/\/www.facebook.com\/NDBanneux\/","article_published_time":"2024-11-07T22:32:07+00:00","og_image":[{"width":1448,"height":2048,"url":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2024\/11\/affiche-2024-scaled.jpg","type":"image\/jpeg"}],"author":"Fabian Delarbre","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Fabian Delarbre","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/banneux-nd.be\/es\/8eme-journee-mondiale-des-pauvres\/#article","isPartOf":{"@id":"https:\/\/banneux-nd.be\/es\/8eme-journee-mondiale-des-pauvres\/"},"author":{"name":"Fabian Delarbre","@id":"https:\/\/banneux-nd.be\/es\/#\/schema\/person\/0d1a4402510d5ffa26dcb30a942708b2"},"headline":"8\u00e8me journ\u00e9e mondiale des Pauvres","datePublished":"2024-11-07T22:32:07+00:00","mainEntityOfPage":{"@id":"https:\/\/banneux-nd.be\/es\/8eme-journee-mondiale-des-pauvres\/"},"wordCount":524,"commentCount":0,"image":{"@id":"https:\/\/banneux-nd.be\/es\/8eme-journee-mondiale-des-pauvres\/#primaryimage"},"thumbnailUrl":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2024\/11\/affiche-2024-scaled.jpg","keywords":["journ\u00e9e mondiale des pauvres","Sanctuaire de Banneux","Vierge des Pauvres"],"articleSection":["A la Une"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/banneux-nd.be\/es\/8eme-journee-mondiale-des-pauvres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/banneux-nd.be\/es\/8eme-journee-mondiale-des-pauvres\/","url":"https:\/\/banneux-nd.be\/es\/8eme-journee-mondiale-des-pauvres\/","name":"8\u00e8me journ\u00e9e mondiale des Pauvres - Banneux Notre-Dame","isPartOf":{"@id":"https:\/\/banneux-nd.be\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/banneux-nd.be\/es\/8eme-journee-mondiale-des-pauvres\/#primaryimage"},"image":{"@id":"https:\/\/banneux-nd.be\/es\/8eme-journee-mondiale-des-pauvres\/#primaryimage"},"thumbnailUrl":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2024\/11\/affiche-2024-scaled.jpg","datePublished":"2024-11-07T22:32:07+00:00","author":{"@id":"https:\/\/banneux-nd.be\/es\/#\/schema\/person\/0d1a4402510d5ffa26dcb30a942708b2"},"breadcrumb":{"@id":"https:\/\/banneux-nd.be\/es\/8eme-journee-mondiale-des-pauvres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/banneux-nd.be\/es\/8eme-journee-mondiale-des-pauvres\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/banneux-nd.be\/es\/8eme-journee-mondiale-des-pauvres\/#primaryimage","url":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2024\/11\/affiche-2024-scaled.jpg","contentUrl":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2024\/11\/affiche-2024-scaled.jpg","width":1448,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/banneux-nd.be\/es\/8eme-journee-mondiale-des-pauvres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/banneux-nd.be\/es\/"},{"@type":"ListItem","position":2,"name":"8\u00e8me journ\u00e9e mondiale des Pauvres"}]},{"@type":"WebSite","@id":"https:\/\/banneux-nd.be\/es\/#website","url":"https:\/\/banneux-nd.be\/es\/","name":"Banneux Notre-Dame","description":"Sanctuaire de la Vierge des Pauvres (Belgique)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/banneux-nd.be\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/banneux-nd.be\/es\/#\/schema\/person\/0d1a4402510d5ffa26dcb30a942708b2","name":"Fabian Delarbre","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g","caption":"Fabian Delarbre"},"url":"https:\/\/banneux-nd.be\/es\/author\/sanctuaire\/"}]}},"author_meta":{"display_name":"Fabian Delarbre","author_link":"https:\/\/banneux-nd.be\/es\/author\/sanctuaire\/"},"featured_img":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2024\/11\/affiche-2024-212x300.jpg","jetpack_publicize_connections":[],"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/banneux-nd.be\/fr\/category\/a-la-une\/\" class=\"advgb-post-tax-term\">A la Une<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">A la Une<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/banneux-nd.be\/fr\/category\/a-la-une\/\" class=\"advgb-post-tax-term\">journ\u00e9e mondiale des pauvres<\/a>","<a href=\"https:\/\/banneux-nd.be\/fr\/category\/a-la-une\/\" class=\"advgb-post-tax-term\">Sanctuaire de Banneux<\/a>","<a href=\"https:\/\/banneux-nd.be\/fr\/category\/a-la-une\/\" class=\"advgb-post-tax-term\">Vierge des Pauvres<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">journ\u00e9e mondiale des pauvres<\/span>","<span class=\"advgb-post-tax-term\">Sanctuaire de Banneux<\/span>","<span class=\"advgb-post-tax-term\">Vierge des Pauvres<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 a\u00f1os hace","modified":"Actualizado 2 a\u00f1os hace"},"absolute_dates":{"created":"Publicado el 7 de noviembre de 2024","modified":"Actualizado el 7 de noviembre de 2024"},"absolute_dates_time":{"created":"Publicado el 7 de noviembre de 2024 23:32","modified":"Actualizado el 7 de noviembre de 2024 23:32"},"featured_img_caption":"","series_order":"","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2024\/11\/affiche-2024-scaled.jpg","_links":{"self":[{"href":"https:\/\/banneux-nd.be\/es\/wp-json\/wp\/v2\/posts\/19454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/banneux-nd.be\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/banneux-nd.be\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/banneux-nd.be\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/banneux-nd.be\/es\/wp-json\/wp\/v2\/comments?post=19454"}],"version-history":[{"count":2,"href":"https:\/\/banneux-nd.be\/es\/wp-json\/wp\/v2\/posts\/19454\/revisions"}],"predecessor-version":[{"id":19470,"href":"https:\/\/banneux-nd.be\/es\/wp-json\/wp\/v2\/posts\/19454\/revisions\/19470"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/banneux-nd.be\/es\/wp-json\/wp\/v2\/media\/19455"}],"wp:attachment":[{"href":"https:\/\/banneux-nd.be\/es\/wp-json\/wp\/v2\/media?parent=19454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/banneux-nd.be\/es\/wp-json\/wp\/v2\/categories?post=19454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/banneux-nd.be\/es\/wp-json\/wp\/v2\/tags?post=19454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}