{"id":14024,"date":"2020-12-19T10:00:00","date_gmt":"2020-12-19T09:00:00","guid":{"rendered":"https:\/\/banneux-nd.be\/?p=14024"},"modified":"2021-04-02T17:04:22","modified_gmt":"2021-04-02T15:04:22","slug":"emmanuel","status":"publish","type":"post","link":"https:\/\/banneux-nd.be\/it\/emmanuel\/","title":{"rendered":"Emmanuel"},"content":{"rendered":"\n<p style=\"text-align: justify;\">\u00ab\u00a0Le Seigneur est avec toi, David\u00a0!\u00a0\u00bb \u00ab\u00a0Le Seigneur est avec toi, Marie\u00a0!\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Le Seigneur assure ses deux \u00e9lus, David et Marie, de sa fid\u00e8le pr\u00e9sence \u00e0 leurs c\u00f4t\u00e9s. Il s\u2019agit l\u00e0 d\u2019une constante dans toute l\u2019histoire de Dieu avec les hommes\u00a0: \u00ab\u00a0Je suis avec vous, je suis avec toi. Pourquoi avoir peur\u00a0?\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">D\u2019ailleurs, David en a fait l\u2019exp\u00e9rience. Il \u00e9tait tout jeune quand le Seigneur l\u2019a choisi comme futur roi d\u2019Isra\u00ebl \u00e0 la place de Sa\u00fcl. Mais Sa\u00fcl n\u2019a pas l\u2019intention de l\u00e2cher le pouvoir et de descendre de son tr\u00f4ne. Il se pr\u00e9pare m\u00eame \u00e0 faire mourir David. Mais Dieu est l\u00e0 et le sauve de la main de l\u2019adversaire. \u00ab\u00a0J\u2019ai \u00e9t\u00e9 avec toi dans tout ce que tu as fait,\u00a0\u00bb rappelle le Seigneur dans la premi\u00e8re lecture de ce jour.<\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s la mort de Sa\u00fcl, David monte sur le tr\u00f4ne et finira par conqu\u00e9rir la ville de J\u00e9rusalem dont il fera sa capitale. Il s\u2019y installe dans un palais en bois de c\u00e8dre. Mais une nuit, il se r\u00e9veille en sursaut\u00a0: \u00ab\u00a0Il y a quelque chose qui ne va pas\u00a0: <em>Moi, j\u2019habite une belle maison alors que l\u2019arche d\u2019alliance o\u00f9 r\u00e9side Dieu se trouve sous la tente. Il faut que je construise une maison somptueuse pour le Seigneur.<\/em>\u00a0\u00bb Il confie son projet au proph\u00e8te Nathan qui n\u2019y voit aucun probl\u00e8me\u00a0: \u00ab\u00a0Tout ce que tu as l\u2019intention de faire, fais-le car le Seigneur est avec toi.\u00a0\u00bb Tout semble donc en ordre.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00ab\u00a0Humblement v\u00f4tre\u00a0\u00bb <\/strong><\/p>\n<p style=\"text-align: justify;\">Mais Dieu intervient et met le hol\u00e0. Il se fait du souci pour son roi. Il se rend compte qu\u2019imperceptiblement, un glissement est en train de se produire dans le c\u0153ur de David, un glissement que le Seigneur ne peut pas approuver. Un s\u00e9rieux d\u00e9s\u00e9quilibre est en train de s\u2019installer dans la vie de l\u2019\u00e9lu.<\/p>\n<p style=\"text-align: justify;\">Tant qu\u2019il \u00e9tait petit et faible, David s\u2019en remettait \u00e0 Dieu\u00a0: \u00ab\u00a0Dieu est avec moi et agira en ma faveur.\u00a0\u00bb Il laisse faire Dieu. Maintenant qu\u2019il est devenu grand et puissant, c\u2019est lui qui fera pour Dieu. En for\u00e7ant un peu on pourrait dire\u00a0: le petit berger avait conscience de sa faiblesse et avait besoin de l\u2019aide de Dieu. Le grand roi se sent fort et puissant, et Dieu devrait \u00eatre content de pouvoir compter et s\u2019appuyer sur lui. C\u2019est un peu le monde \u00e0 l\u2019envers. Chez le proph\u00e8te Isa\u00efe, le Seigneur sourit parfois et se moque un peu de notre sottise\u00a0: \u00ab\u00a0La hache fait-elle la fi\u00e8re contre celui qui la brandit\u00a0? La scie s\u2019\u00e9l\u00e8ve-t-elle contre celui qui la manie\u00a0?\u00a0\u00bb (Is 10, 15) Il est temps que Dieu mette les pendules \u00e0 l\u2019heure. \u00ab\u00a0C\u2019est moi qui te b\u00e2tirai une maison\u00a0\u00bb, dit-il \u00e0 David. David comprend que le Seigneur joue sur les mots. La maison de David n\u2019est pas le palais en c\u00e8dre, mais la descendance, la maisonn\u00e9e de David. Et il faut que les descendants se laissent faire par le Seigneur pour rester fid\u00e8les.<\/p>\n<p style=\"text-align: justify;\">C\u2019est l\u00e0 que se pose le vrai probl\u00e8me. La maison de David a connu des fortunes diverses. Certains rois ont fait de leur mieux pour rester fid\u00e8le, d\u2019autres ont fait n\u2019importe quoi et ont d\u00e9plu \u00e0 leur Dieu. Au temps de Joseph et de Marie, il n\u2019y a plus de descendant de David sur le tr\u00f4ne royal. La grande dynastie davidique a perdu le pouvoir et le prestige.<\/p>\n<p style=\"text-align: justify;\">Mais comme il tient \u00e0 son plan de salut, comme il veut \u00e0 tout prix faire r\u00e9ussir l\u2019histoire sainte, le Seigneur prend encore une fois l\u2019initiative. Il a rep\u00e9r\u00e9 \u00e0 Nazareth celle qui donnera naissance au Fils de David que le monde attend. \u00ab\u00a0Le Seigneur lui donnera le tr\u00f4ne de David son p\u00e8re, et son r\u00e8gne n\u2019aura pas de fin.\u00a0\u00bb<\/p>\n<p><strong>Faire ou se laisser faire\u00a0? <\/strong><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"wp-image-14025 alignleft lazyload\" data-src=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/12\/AnnonciationRodez_copie_20170322093611732019.jpg\" alt=\"\" width=\"416\" height=\"262\" data-srcset=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/12\/AnnonciationRodez_copie_20170322093611732019.jpg 600w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/12\/AnnonciationRodez_copie_20170322093611732019-300x189.jpg 300w\" data-sizes=\"(max-width: 416px) 100vw, 416px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 416px; --smush-placeholder-aspect-ratio: 416\/262;\" \/>Marie se sait petite et impuissante face \u00e0 cet appel. \u00ab\u00a0Comment cela va-t-il se faire puisque je suis vierge\u00a0?\u00a0\u00bb Elle a exactement l\u2019attitude qu\u2019il faut pour \u00eatre partie prenante du projet de Dieu. Elle sait que de son c\u00f4t\u00e9 elle ne peut pas faire valoir ses capacit\u00e9s et ses forces. En cela elle est parfaitement accord\u00e9e \u00e0 Dieu\u00a0: \u00ab\u00a0L\u2019Esprit saint viendra sur toi et la force du Tr\u00e8s-Haut te prendra sous son ombre\u00a0!\u00a0\u00bb Elle laisse faire Dieu tout en acceptant sa part modeste\u00a0: sa disponibilit\u00e9 \u00e0 l\u2019agir divin. \u00ab\u00a0Voici la servante du Seigneur, que tout se passe pour moi selon ta parole.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Ce qui est impossible \u00e0 l\u2019homme est possible \u00e0 Dieu, si nous le laissons faire\u00a0!<\/p>\n<p style=\"text-align: justify;\">Bien plus que du temps de David ou du temps de Marie, nous vivons dans une culture qui souligne l\u2019agir de l\u2019homme, et nous serions tent\u00e9s, comme David, de prendre les choses en main. Nous allons faire pour Dieu\u00a0: nous essayerons de b\u00e2tir un royaume de justice et de paix par nos propres forces. Il y a beaucoup de chances que \u00e7a ne marche pas.<\/p>\n<p style=\"text-align: justify;\">S\u2019en remettre \u00e0 Dieu\u00a0! Etre serviteur\/servante du Seigneur\u00a0: alors, \u00e0 travers nous, il pourra \u0153uvrer. Ceux qui laissent ainsi faire le Seigneur vont exp\u00e9rimenter quelque chose de curieux. Ils seront d\u00e9pass\u00e9s par ce qui leur arrive. David et Marie en savent quelque chose\u00a0! Dieu plus grand que nos petits projets\u00a0!<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0Dieu est \u00e0 l\u2019\u0153uvre en cet \u00e2ge, ces temps sont les derniers, Dieu est \u00e0 l\u2019\u0153uvre en cet \u00e2ge, son jour va se lever. Ne doutons pas du jour qui vient, la nuit touche \u00e0 sa fin, et l\u2019\u00e9clat du Seigneur remplira l\u2019univers mieux que l\u2019eau ne couvre les mers.\u00a0\u00bb<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Abb\u00e9 Leo Palm<\/p>\n<hr \/>\n<p>\u00a0<\/p>\n\n\n\n<p style=\"text-align: center;\"><strong>Pri\u00e8re universelle pour le quatri\u00e8me <\/strong><strong>dimanche de l\u2019Avent B<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><em><strong>Le Seigneur vient\u00a0: que notre pri\u00e8re commune pour le monde et pour l\u2019Eglise h\u00e2te sa venue au milieu de nous\u00a0:<\/strong><\/em><\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Refrain : Sauve-nous, Seigneur, dans ton amour !<\/p>\n<ul>\n<li>\u00ab\u00a0Le myst\u00e8re de Dieu \u00e9tait rest\u00e9 dans le silence depuis toujours, mais aujourd\u2019hui, il est manifest\u00e9.\u00a0\u00bb Seigneur, augmente en nous la foi en ton Fils unique. Que ton Esprit nous r\u00e9v\u00e8le ton visage et l\u2019amour infini dont tu nous aimes. Ensemble, chantons.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<ul>\n<li>\u00ab\u00a0Ce myst\u00e8re est port\u00e9 \u00e0 la connaissance de toutes les nations.\u00a0\u00bb Seigneur, sois la lumi\u00e8re de tous les missionnaires, que ton Esprit Saint leur communique l\u2019enthousiasme et le dynamisme dont ils ont besoin pour annoncer l\u2019Evangile du Christ. Ensemble, chantons.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<ul>\n<li>\u00ab\u00a0J\u2019ai \u00e9t\u00e9 avec toi dans tout ce que tu as fait.\u00a0\u00bb Seigneur, manifeste ta pr\u00e9sence aupr\u00e8s de ceux qui se mettent au service des plus pr\u00e9caris\u00e9s de nos soci\u00e9t\u00e9s. Que ton Esprit renforce les liens de solidarit\u00e9 et de fraternit\u00e9 entre les hommes. Ensemble, chantons.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<ul>\n<li>\u00ab\u00a0Sois sans crainte, tu as trouv\u00e9 gr\u00e2ce aupr\u00e8s de Dieu.\u00a0\u00bb Seigneur, nous te confions tous ceux qui ont peur, nous prions pour toutes les victimes de la pand\u00e9mie, de la terreur et de la violence. Que ton Esprit Saint touche les c\u0153urs de pierre et les transforme en c\u0153urs de chair. Ensemble, chantons.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p><em><strong>Dieu Sauveur, tu as assum\u00e9 notre humanit\u00e9 en J\u00e9sus, ton Fils bien-aim\u00e9. Gloire \u00e0 toi, le seul sage, par J\u00e9sus Christ et pour les si\u00e8cles des si\u00e8cles.<\/strong><\/em><\/p>\n<hr \/>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marie se sait petite et impuissante face \u00e0 cet appel. \u00ab Comment cela va-t-il se faire puisque je suis vierge ? \u00bb Elle a exactement l\u2019attitude qu\u2019il faut pour \u00eatre partie prenante du projet de Dieu. Elle sait que de son c\u00f4t\u00e9 elle ne peut pas faire valoir ses capacit\u00e9s et ses forces. En cela elle est parfaitement accord\u00e9e \u00e0 Dieu : \u00ab L\u2019Esprit saint viendra sur toi et la force du Tr\u00e8s-Haut te prendra sous son ombre ! \u00bb Elle laisse faire Dieu tout en acceptant sa part modeste : sa disponibilit\u00e9 \u00e0 l\u2019agir divin. \u00ab Voici la servante du Seigneur, que tout se passe pour moi selon ta parole. \u00bb<\/p>\n","protected":false},"author":10,"featured_media":14025,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[63],"tags":[209],"class_list":["post-14024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-homelies","tag-sanctuaire-de-banneux"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emmanuel - Banneux Notre-Dame<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/banneux-nd.be\/it\/emmanuel\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emmanuel - Banneux Notre-Dame\" \/>\n<meta property=\"og:description\" content=\"Marie se sait petite et impuissante face \u00e0 cet appel. \u00ab Comment cela va-t-il se faire puisque je suis vierge ? \u00bb Elle a exactement l\u2019attitude qu\u2019il faut pour \u00eatre partie prenante du projet de Dieu. Elle sait que de son c\u00f4t\u00e9 elle ne peut pas faire valoir ses capacit\u00e9s et ses forces. En cela elle est parfaitement accord\u00e9e \u00e0 Dieu : \u00ab L\u2019Esprit saint viendra sur toi et la force du Tr\u00e8s-Haut te prendra sous son ombre ! \u00bb Elle laisse faire Dieu tout en acceptant sa part modeste : sa disponibilit\u00e9 \u00e0 l\u2019agir divin. \u00ab Voici la servante du Seigneur, que tout se passe pour moi selon ta parole. \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/banneux-nd.be\/it\/emmanuel\/\" \/>\n<meta property=\"og:site_name\" content=\"Banneux Notre-Dame\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NDBanneux\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-19T09:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-02T15:04:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/12\/AnnonciationRodez_copie_20170322093611732019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"377\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fabian Delarbre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabian Delarbre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/emmanuel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/emmanuel\\\/\"},\"author\":{\"name\":\"Fabian Delarbre\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/#\\\/schema\\\/person\\\/0d1a4402510d5ffa26dcb30a942708b2\"},\"headline\":\"Emmanuel\",\"datePublished\":\"2020-12-19T09:00:00+00:00\",\"dateModified\":\"2021-04-02T15:04:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/emmanuel\\\/\"},\"wordCount\":1258,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/emmanuel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/AnnonciationRodez_copie_20170322093611732019.jpg\",\"keywords\":[\"Sanctuaire de Banneux\"],\"articleSection\":[\"Hom\u00e9lies\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/banneux-nd.be\\\/it\\\/emmanuel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/emmanuel\\\/\",\"url\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/emmanuel\\\/\",\"name\":\"Emmanuel - Banneux Notre-Dame\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/emmanuel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/emmanuel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/AnnonciationRodez_copie_20170322093611732019.jpg\",\"datePublished\":\"2020-12-19T09:00:00+00:00\",\"dateModified\":\"2021-04-02T15:04:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/#\\\/schema\\\/person\\\/0d1a4402510d5ffa26dcb30a942708b2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/emmanuel\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/banneux-nd.be\\\/it\\\/emmanuel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/emmanuel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/AnnonciationRodez_copie_20170322093611732019.jpg\",\"contentUrl\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/AnnonciationRodez_copie_20170322093611732019.jpg\",\"width\":600,\"height\":377},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/emmanuel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emmanuel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/\",\"name\":\"Banneux Notre-Dame\",\"description\":\"Sanctuaire de la Vierge des Pauvres (Belgique)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/#\\\/schema\\\/person\\\/0d1a4402510d5ffa26dcb30a942708b2\",\"name\":\"Fabian Delarbre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g\",\"caption\":\"Fabian Delarbre\"},\"url\":\"https:\\\/\\\/banneux-nd.be\\\/it\\\/author\\\/sanctuaire\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emmanuel - Banneux Notre-Dame","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/banneux-nd.be\/it\/emmanuel\/","og_locale":"it_IT","og_type":"article","og_title":"Emmanuel - Banneux Notre-Dame","og_description":"Marie se sait petite et impuissante face \u00e0 cet appel. \u00ab Comment cela va-t-il se faire puisque je suis vierge ? \u00bb Elle a exactement l\u2019attitude qu\u2019il faut pour \u00eatre partie prenante du projet de Dieu. Elle sait que de son c\u00f4t\u00e9 elle ne peut pas faire valoir ses capacit\u00e9s et ses forces. En cela elle est parfaitement accord\u00e9e \u00e0 Dieu : \u00ab L\u2019Esprit saint viendra sur toi et la force du Tr\u00e8s-Haut te prendra sous son ombre ! \u00bb Elle laisse faire Dieu tout en acceptant sa part modeste : sa disponibilit\u00e9 \u00e0 l\u2019agir divin. \u00ab Voici la servante du Seigneur, que tout se passe pour moi selon ta parole. \u00bb","og_url":"https:\/\/banneux-nd.be\/it\/emmanuel\/","og_site_name":"Banneux Notre-Dame","article_publisher":"https:\/\/www.facebook.com\/NDBanneux\/","article_published_time":"2020-12-19T09:00:00+00:00","article_modified_time":"2021-04-02T15:04:22+00:00","og_image":[{"width":600,"height":377,"url":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/12\/AnnonciationRodez_copie_20170322093611732019.jpg","type":"image\/jpeg"}],"author":"Fabian Delarbre","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Fabian Delarbre","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/banneux-nd.be\/it\/emmanuel\/#article","isPartOf":{"@id":"https:\/\/banneux-nd.be\/it\/emmanuel\/"},"author":{"name":"Fabian Delarbre","@id":"https:\/\/banneux-nd.be\/it\/#\/schema\/person\/0d1a4402510d5ffa26dcb30a942708b2"},"headline":"Emmanuel","datePublished":"2020-12-19T09:00:00+00:00","dateModified":"2021-04-02T15:04:22+00:00","mainEntityOfPage":{"@id":"https:\/\/banneux-nd.be\/it\/emmanuel\/"},"wordCount":1258,"commentCount":0,"image":{"@id":"https:\/\/banneux-nd.be\/it\/emmanuel\/#primaryimage"},"thumbnailUrl":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/12\/AnnonciationRodez_copie_20170322093611732019.jpg","keywords":["Sanctuaire de Banneux"],"articleSection":["Hom\u00e9lies"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/banneux-nd.be\/it\/emmanuel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/banneux-nd.be\/it\/emmanuel\/","url":"https:\/\/banneux-nd.be\/it\/emmanuel\/","name":"Emmanuel - Banneux Notre-Dame","isPartOf":{"@id":"https:\/\/banneux-nd.be\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/banneux-nd.be\/it\/emmanuel\/#primaryimage"},"image":{"@id":"https:\/\/banneux-nd.be\/it\/emmanuel\/#primaryimage"},"thumbnailUrl":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/12\/AnnonciationRodez_copie_20170322093611732019.jpg","datePublished":"2020-12-19T09:00:00+00:00","dateModified":"2021-04-02T15:04:22+00:00","author":{"@id":"https:\/\/banneux-nd.be\/it\/#\/schema\/person\/0d1a4402510d5ffa26dcb30a942708b2"},"breadcrumb":{"@id":"https:\/\/banneux-nd.be\/it\/emmanuel\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/banneux-nd.be\/it\/emmanuel\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/banneux-nd.be\/it\/emmanuel\/#primaryimage","url":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/12\/AnnonciationRodez_copie_20170322093611732019.jpg","contentUrl":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/12\/AnnonciationRodez_copie_20170322093611732019.jpg","width":600,"height":377},{"@type":"BreadcrumbList","@id":"https:\/\/banneux-nd.be\/it\/emmanuel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/banneux-nd.be\/it\/"},{"@type":"ListItem","position":2,"name":"Emmanuel"}]},{"@type":"WebSite","@id":"https:\/\/banneux-nd.be\/it\/#website","url":"https:\/\/banneux-nd.be\/it\/","name":"Banneux Notre-Dame","description":"Sanctuaire de la Vierge des Pauvres (Belgique)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/banneux-nd.be\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/banneux-nd.be\/it\/#\/schema\/person\/0d1a4402510d5ffa26dcb30a942708b2","name":"Fabian Delarbre","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g","caption":"Fabian Delarbre"},"url":"https:\/\/banneux-nd.be\/it\/author\/sanctuaire\/"}]}},"author_meta":{"display_name":"Fabian Delarbre","author_link":"https:\/\/banneux-nd.be\/it\/author\/sanctuaire\/"},"featured_img":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/12\/AnnonciationRodez_copie_20170322093611732019-300x189.jpg","jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2020\/12\/AnnonciationRodez_copie_20170322093611732019.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/banneux-nd.be\/fr\/category\/homelies\/\" class=\"advgb-post-tax-term\">Hom\u00e9lies<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Hom\u00e9lies<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/banneux-nd.be\/fr\/category\/homelies\/\" class=\"advgb-post-tax-term\">Sanctuaire de Banneux<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Sanctuaire de Banneux<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Pubblicato 6 anni fa","modified":"Aggiornato 5 anni fa"},"absolute_dates":{"created":"Pubblicato il 19 Dicembre 2020","modified":"Aggiornato il 2 Aprile 2021"},"absolute_dates_time":{"created":"Pubblicato il 19 Dicembre 2020 10:00","modified":"Aggiornato il 2 Aprile 2021 17:04"},"featured_img_caption":"","series_order":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/banneux-nd.be\/it\/wp-json\/wp\/v2\/posts\/14024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/banneux-nd.be\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/banneux-nd.be\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/banneux-nd.be\/it\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/banneux-nd.be\/it\/wp-json\/wp\/v2\/comments?post=14024"}],"version-history":[{"count":5,"href":"https:\/\/banneux-nd.be\/it\/wp-json\/wp\/v2\/posts\/14024\/revisions"}],"predecessor-version":[{"id":14036,"href":"https:\/\/banneux-nd.be\/it\/wp-json\/wp\/v2\/posts\/14024\/revisions\/14036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/banneux-nd.be\/it\/wp-json\/wp\/v2\/media\/14025"}],"wp:attachment":[{"href":"https:\/\/banneux-nd.be\/it\/wp-json\/wp\/v2\/media?parent=14024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/banneux-nd.be\/it\/wp-json\/wp\/v2\/categories?post=14024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/banneux-nd.be\/it\/wp-json\/wp\/v2\/tags?post=14024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}