{"id":12318,"date":"2019-11-09T14:53:49","date_gmt":"2019-11-09T13:53:49","guid":{"rendered":"https:\/\/www.banneux-nd.be\/?p=12318"},"modified":"2021-04-02T17:26:02","modified_gmt":"2021-04-02T15:26:02","slug":"une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019","status":"publish","type":"post","link":"https:\/\/banneux-nd.be\/nl\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\/","title":{"rendered":"Une statue de la Vierge des Pauvres  \u00e0 la Basilique Saint Pierre  pour la journ\u00e9e mondiale des Pauvres  le 17 novembre 2019"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">Lors d\u2019un congr\u00e8s de cat\u00e9chistes \u00e0 Rome, le P\u00e8re Jorge\nBarros \u2013 pr\u00eatre chilien dont le t\u00e9moignage se trouve en annexe 3 \u2013 a rencontr\u00e9\nle secr\u00e9taire du Conseil pontifical pour la promotion de la nouvelle\n\u00e9vang\u00e9lisation, Mgr Jos\u00e9 Octavio Ruiz Arenas.&nbsp;\nIls ont discut\u00e9 de la Journ\u00e9e mondiale des Pauvres.&nbsp; Le pape Fran\u00e7ois a eu l\u2019heureuse initiative\nde cette journ\u00e9e, traduisant ainsi son souci permanent pour les d\u00e9munis et sa\nvolont\u00e9 de sensibiliser toute l\u2019Eglise et toute l\u2019humanit\u00e9 \u00e0 cet enjeu\nessentiel.&nbsp; L\u2019id\u00e9e d\u2019un lien avec Banneux\na jailli.&nbsp; Il nous l\u2019a souffl\u00e9e \u00e0\nl\u2019oreille. Ce pr\u00eatre chilien a pass\u00e9 ses premi\u00e8res ann\u00e9es de sacerdoce dans un\nquartier pauvre de Santiago de Chile, dans la paroisse de la \u00ab&nbsp;Vierge des\nPauvres&nbsp;\u00bb. Il y est devenu le t\u00e9moin \u00e9merveill\u00e9 de l\u2019action bienfaisante\nde Notre-Dame de Banneux aupr\u00e8s des marginaux de nos soci\u00e9t\u00e9s. <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Nous avons donc pris contact avec Monseigneur Rino Fisichella, Pr\u00e9sident\ndu Conseil pontifical pour la promotion de la nouvelle \u00e9vang\u00e9lisation. &nbsp;C\u2019est avec beaucoup de joie que nous l\u2019avons\nrencontr\u00e9 \u00e0 Rome lors du premier congr\u00e8s pour les recteurs et animateurs de\nsanctuaires.&nbsp; Il nous a partag\u00e9 \u00e9galement\nson souhait de voir la statue de la Vierge des Pauvres dans la Basilique Saint\nPierre.&nbsp; A deux reprises, le Sanctuaire a d\u00e9j\u00e0 offert une statue aux papes\nPie XII et Jean XXIII (voir annexe 1).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"653\" data-src=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/Statue-place-St-Pierre-juin-1959-1024x653.jpg\" alt=\"\" class=\"wp-image-12326 lazyload\" data-srcset=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/Statue-place-St-Pierre-juin-1959-1024x653.jpg 1024w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/Statue-place-St-Pierre-juin-1959-300x191.jpg 300w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/Statue-place-St-Pierre-juin-1959-768x489.jpg 768w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/Statue-place-St-Pierre-juin-1959.jpg 1544w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/653;\" \/><figcaption>Statue place St Pierre juin 1959<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Mgr Fisichella a alors exprim\u00e9 le souhait de visiter\nBanneux&nbsp;: il est venu pr\u00e9sider les c\u00e9l\u00e9brations de la F\u00eate-Dieu, le 23\njuin dernier.&nbsp; Occasion r\u00eav\u00e9e d\u2019une\nvisite guid\u00e9e des lieux et d\u2019une explication du Message de la Belle Dame.&nbsp; Il a d\u00e9couvert le havre de paix que Marie\ns\u2019est r\u00e9serv\u00e9.&nbsp; Il est retourn\u00e9 \u00e0 Rome,\nenchant\u00e9 de son p\u00e8lerinage.&nbsp; Lors de la\nmesse internationale, le recteur, l\u2019Abb\u00e9 Palm, lui a remis un dossier, appuy\u00e9\npar notre \u00e9v\u00eaque, Mgr Delville, et par le Nonce apostolique, Mgr Kasujja.&nbsp;&nbsp; Le 2 octobre dernier, nous avons re\u00e7u une\nr\u00e9ponse positive \u00e0 notre demande&nbsp;: <em>\u00ab&nbsp;Vous\naurez la possibilit\u00e9, en accord avec le Bureau des c\u00e9l\u00e9brations liturgiques du\nSouverain Pontife, de placer la statue de la Vierge \u00e0 l\u2019autel de la Confession\ndans la Basilique Saint Pierre, \u00e0 l\u2019occasion de la c\u00e9l\u00e9bration eucharistique du\ndimanche 17 novembre prochain, qui sera pr\u00e9sid\u00e9e par le Pape Fran\u00e7ois.&nbsp;\u00bb<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" data-src=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/Statue-dans-la-Basilique-St-Pierre-derri\u00e8re-le-Pape-Jean-XXIII-27-juin-1959-1024x725.jpg\" alt=\"\" class=\"wp-image-12319 lazyload\" width=\"640\" height=\"452\" data-srcset=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/Statue-dans-la-Basilique-St-Pierre-derri\u00e8re-le-Pape-Jean-XXIII-27-juin-1959-1024x725.jpg 1024w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/Statue-dans-la-Basilique-St-Pierre-derri\u00e8re-le-Pape-Jean-XXIII-27-juin-1959-300x212.jpg 300w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/Statue-dans-la-Basilique-St-Pierre-derri\u00e8re-le-Pape-Jean-XXIII-27-juin-1959-768x544.jpg 768w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/Statue-dans-la-Basilique-St-Pierre-derri\u00e8re-le-Pape-Jean-XXIII-27-juin-1959.jpg 2048w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/452;\" \/><figcaption>Statue dans la Basilique St Pierre, derri\u00e8re le Pape Jean XXIII &#8211; 27 juin 1959<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Nous allons offrir au Saint P\u00e8re trois statues de Notre-Dame\nde Banneux pour la journ\u00e9e mondiale des Pauvres.&nbsp;&nbsp; (voir Annexe 2)<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>1 de 65 cm en\nbois pour le Saint P\u00e8re<ul><li>1 de 1,35 m pour\nque le Saint P\u00e8re l\u2019offre \u00e0 un quartier pauvre de Rome, d\u2019Argentine, ou\nd\u2019ailleurs.<\/li><\/ul><ul><li>1 de 1,35 m pour\nla Basilique St Pierre pour les journ\u00e9es mondiales des Pauvres.<\/li><\/ul><\/li><\/ul>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Le 17 novembre prochain, Mgr Jean-Pierre Delville,\n\u00e9v\u00eaque de Li\u00e8ge, Mr l\u2019abb\u00e9 Heinz Schneider, Mme Marlene Kohnen et Mr Fabian\nDelarbre seront pr\u00e9sents \u00e0 Rome pour repr\u00e9senter le Sanctuaire de Banneux.<\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Depuis la premi\u00e8re\njourn\u00e9e mondiale des Pauvres, notre sanctuaire organise, lui aussi, une journ\u00e9e\ndans un esprit de fraternit\u00e9&nbsp;: Nous nous rassemblons sous le signe de la convivialit\u00e9\net de la fraternit\u00e9 car au fond, nous nous retrouverons tous entre\npauvres.&nbsp; La pauvret\u00e9 n\u2019est pas que\nfinanci\u00e8re ou physique, elle est aussi psychologique, spirituelle, m\u00e9dicale,\nmorale vous le savez bien.&nbsp; La Pauvret\u00e9\nc\u2019est aussi l\u2019isolement, l\u2019exclusion familiale ou sociale, la malchance, le\nmal-\u00eatre, la d\u00e9pression, la douleur, le manque de dignit\u00e9, d\u2019amour, de confort,\nd\u2019esp\u00e9rance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Programme de la journ\u00e9e \u00e0 Banneux&nbsp;:<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>11h15&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Messe pr\u00e9sid\u00e9e par l\u2019abb\u00e9 Palm, recteur<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>et anim\u00e9e par la chorale du\nPoverello<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>12h30&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Repas&nbsp;: Auberge espagnole \u2013<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Nous partagerons ce que\nchacun aura apport\u00e9.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/dossier-presse-Journ\u00e9e-des-Pauvres-2019.pdf\">dossier de presse &#8211; Journ\u00e9e-des-Pauvres-2019<\/a><a href=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/dossier-presse-Journ\u00e9e-des-Pauvres-2019.pdf\" class=\"wp-block-file__button\" download>T\u00e9l\u00e9charger<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Une statue de la Vierge des Pauvres  \u00e0 la Basilique Saint Pierre  pour la journ\u00e9e mondiale des Pauvres  le 17 novembre 2019.<\/p>\n","protected":false},"author":10,"featured_media":12326,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11],"tags":[195,134,196,194],"class_list":["post-12318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-info","tag-banneux-4","tag-journee-mondiale-des-pauvres","tag-rome-vatican","tag-vierge-des-pauvres"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Une statue de la Vierge des Pauvres \u00e0 la Basilique Saint Pierre pour la journ\u00e9e mondiale des Pauvres le 17 novembre 2019 - Banneux Notre-Dame<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/banneux-nd.be\/nl\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une statue de la Vierge des Pauvres \u00e0 la Basilique Saint Pierre pour la journ\u00e9e mondiale des Pauvres le 17 novembre 2019 - Banneux Notre-Dame\" \/>\n<meta property=\"og:description\" content=\"Une statue de la Vierge des Pauvres \u00e0 la Basilique Saint Pierre pour la journ\u00e9e mondiale des Pauvres le 17 novembre 2019.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/banneux-nd.be\/nl\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Banneux Notre-Dame\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NDBanneux\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-09T13:53:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-02T15:26:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/Statue-place-St-Pierre-juin-1959.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1544\" \/>\n\t<meta property=\"og:image:height\" content=\"984\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fabian Delarbre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabian Delarbre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\\\/\"},\"author\":{\"name\":\"Fabian Delarbre\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/#\\\/schema\\\/person\\\/0d1a4402510d5ffa26dcb30a942708b2\"},\"headline\":\"Une statue de la Vierge des Pauvres \u00e0 la Basilique Saint Pierre pour la journ\u00e9e mondiale des Pauvres le 17 novembre 2019\",\"datePublished\":\"2019-11-09T13:53:49+00:00\",\"dateModified\":\"2021-04-02T15:26:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\\\/\"},\"wordCount\":763,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Statue-place-St-Pierre-juin-1959.jpg\",\"keywords\":[\"Banneux\",\"journ\u00e9e mondiale des pauvres\",\"Rome Vatican\",\"Vierge des Pauvres\"],\"articleSection\":[\"Informations\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\\\/\",\"url\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\\\/\",\"name\":\"Une statue de la Vierge des Pauvres \u00e0 la Basilique Saint Pierre pour la journ\u00e9e mondiale des Pauvres le 17 novembre 2019 - Banneux Notre-Dame\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Statue-place-St-Pierre-juin-1959.jpg\",\"datePublished\":\"2019-11-09T13:53:49+00:00\",\"dateModified\":\"2021-04-02T15:26:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/#\\\/schema\\\/person\\\/0d1a4402510d5ffa26dcb30a942708b2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Statue-place-St-Pierre-juin-1959.jpg\",\"contentUrl\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Statue-place-St-Pierre-juin-1959.jpg\",\"width\":1544,\"height\":984},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Une statue de la Vierge des Pauvres \u00e0 la Basilique Saint Pierre pour la journ\u00e9e mondiale des Pauvres le 17 novembre 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/\",\"name\":\"Banneux Notre-Dame\",\"description\":\"Sanctuaire de la Vierge des Pauvres (Belgique)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/#\\\/schema\\\/person\\\/0d1a4402510d5ffa26dcb30a942708b2\",\"name\":\"Fabian Delarbre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g\",\"caption\":\"Fabian Delarbre\"},\"url\":\"https:\\\/\\\/banneux-nd.be\\\/nl\\\/author\\\/sanctuaire\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Une statue de la Vierge des Pauvres \u00e0 la Basilique Saint Pierre pour la journ\u00e9e mondiale des Pauvres le 17 novembre 2019 - Banneux Notre-Dame","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/banneux-nd.be\/nl\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\/","og_locale":"nl_NL","og_type":"article","og_title":"Une statue de la Vierge des Pauvres \u00e0 la Basilique Saint Pierre pour la journ\u00e9e mondiale des Pauvres le 17 novembre 2019 - Banneux Notre-Dame","og_description":"Une statue de la Vierge des Pauvres \u00e0 la Basilique Saint Pierre pour la journ\u00e9e mondiale des Pauvres le 17 novembre 2019.","og_url":"https:\/\/banneux-nd.be\/nl\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\/","og_site_name":"Banneux Notre-Dame","article_publisher":"https:\/\/www.facebook.com\/NDBanneux\/","article_published_time":"2019-11-09T13:53:49+00:00","article_modified_time":"2021-04-02T15:26:02+00:00","og_image":[{"width":1544,"height":984,"url":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/Statue-place-St-Pierre-juin-1959.jpg","type":"image\/jpeg"}],"author":"Fabian Delarbre","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Fabian Delarbre","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/banneux-nd.be\/nl\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\/#article","isPartOf":{"@id":"https:\/\/banneux-nd.be\/nl\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\/"},"author":{"name":"Fabian Delarbre","@id":"https:\/\/banneux-nd.be\/nl\/#\/schema\/person\/0d1a4402510d5ffa26dcb30a942708b2"},"headline":"Une statue de la Vierge des Pauvres \u00e0 la Basilique Saint Pierre pour la journ\u00e9e mondiale des Pauvres le 17 novembre 2019","datePublished":"2019-11-09T13:53:49+00:00","dateModified":"2021-04-02T15:26:02+00:00","mainEntityOfPage":{"@id":"https:\/\/banneux-nd.be\/nl\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\/"},"wordCount":763,"commentCount":0,"image":{"@id":"https:\/\/banneux-nd.be\/nl\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/Statue-place-St-Pierre-juin-1959.jpg","keywords":["Banneux","journ\u00e9e mondiale des pauvres","Rome Vatican","Vierge des Pauvres"],"articleSection":["Informations"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/banneux-nd.be\/nl\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/banneux-nd.be\/nl\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\/","url":"https:\/\/banneux-nd.be\/nl\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\/","name":"Une statue de la Vierge des Pauvres \u00e0 la Basilique Saint Pierre pour la journ\u00e9e mondiale des Pauvres le 17 novembre 2019 - Banneux Notre-Dame","isPartOf":{"@id":"https:\/\/banneux-nd.be\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/banneux-nd.be\/nl\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\/#primaryimage"},"image":{"@id":"https:\/\/banneux-nd.be\/nl\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/Statue-place-St-Pierre-juin-1959.jpg","datePublished":"2019-11-09T13:53:49+00:00","dateModified":"2021-04-02T15:26:02+00:00","author":{"@id":"https:\/\/banneux-nd.be\/nl\/#\/schema\/person\/0d1a4402510d5ffa26dcb30a942708b2"},"breadcrumb":{"@id":"https:\/\/banneux-nd.be\/nl\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/banneux-nd.be\/nl\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/banneux-nd.be\/nl\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\/#primaryimage","url":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/Statue-place-St-Pierre-juin-1959.jpg","contentUrl":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/Statue-place-St-Pierre-juin-1959.jpg","width":1544,"height":984},{"@type":"BreadcrumbList","@id":"https:\/\/banneux-nd.be\/nl\/une-statue-de-la-vierge-des-pauvres-a-la-basilique-saint-pierre-pour-la-journee-mondiale-des-pauvres-le-17-novembre-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/banneux-nd.be\/nl\/"},{"@type":"ListItem","position":2,"name":"Une statue de la Vierge des Pauvres \u00e0 la Basilique Saint Pierre pour la journ\u00e9e mondiale des Pauvres le 17 novembre 2019"}]},{"@type":"WebSite","@id":"https:\/\/banneux-nd.be\/nl\/#website","url":"https:\/\/banneux-nd.be\/nl\/","name":"Banneux Notre-Dame","description":"Sanctuaire de la Vierge des Pauvres (Belgique)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/banneux-nd.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/banneux-nd.be\/nl\/#\/schema\/person\/0d1a4402510d5ffa26dcb30a942708b2","name":"Fabian Delarbre","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g","caption":"Fabian Delarbre"},"url":"https:\/\/banneux-nd.be\/nl\/author\/sanctuaire\/"}]}},"author_meta":{"display_name":"Fabian Delarbre","author_link":"https:\/\/banneux-nd.be\/nl\/author\/sanctuaire\/"},"featured_img":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/Statue-place-St-Pierre-juin-1959-300x191.jpg","jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2019\/11\/Statue-place-St-Pierre-juin-1959.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/banneux-nd.be\/fr\/category\/info\/\" class=\"advgb-post-tax-term\">Informations<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Informations<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/banneux-nd.be\/fr\/category\/info\/\" class=\"advgb-post-tax-term\">Banneux<\/a>","<a href=\"https:\/\/banneux-nd.be\/fr\/category\/info\/\" class=\"advgb-post-tax-term\">journ\u00e9e mondiale des pauvres<\/a>","<a href=\"https:\/\/banneux-nd.be\/fr\/category\/info\/\" class=\"advgb-post-tax-term\">Rome Vatican<\/a>","<a href=\"https:\/\/banneux-nd.be\/fr\/category\/info\/\" class=\"advgb-post-tax-term\">Vierge des Pauvres<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Banneux<\/span>","<span class=\"advgb-post-tax-term\">journ\u00e9e mondiale des pauvres<\/span>","<span class=\"advgb-post-tax-term\">Rome Vatican<\/span>","<span class=\"advgb-post-tax-term\">Vierge des Pauvres<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Geplaatst 7 years geleden","modified":"Bijgewerkt 5 years geleden"},"absolute_dates":{"created":"Geplaatst op 11\/09\/2019","modified":"Bijgewerkt op 04\/02\/2021"},"absolute_dates_time":{"created":"Geplaatst op 11\/09\/2019 14 h 53 min","modified":"Bijgewerkt op 04\/02\/2021 17 h 26 min"},"featured_img_caption":"","series_order":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/banneux-nd.be\/nl\/wp-json\/wp\/v2\/posts\/12318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/banneux-nd.be\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/banneux-nd.be\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/banneux-nd.be\/nl\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/banneux-nd.be\/nl\/wp-json\/wp\/v2\/comments?post=12318"}],"version-history":[{"count":3,"href":"https:\/\/banneux-nd.be\/nl\/wp-json\/wp\/v2\/posts\/12318\/revisions"}],"predecessor-version":[{"id":12342,"href":"https:\/\/banneux-nd.be\/nl\/wp-json\/wp\/v2\/posts\/12318\/revisions\/12342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/banneux-nd.be\/nl\/wp-json\/wp\/v2\/media\/12326"}],"wp:attachment":[{"href":"https:\/\/banneux-nd.be\/nl\/wp-json\/wp\/v2\/media?parent=12318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/banneux-nd.be\/nl\/wp-json\/wp\/v2\/categories?post=12318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/banneux-nd.be\/nl\/wp-json\/wp\/v2\/tags?post=12318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}