{"id":15409,"date":"2021-05-02T10:51:29","date_gmt":"2021-05-02T08:51:29","guid":{"rendered":"https:\/\/banneux-nd.be\/?p=15409"},"modified":"2021-05-02T10:51:31","modified_gmt":"2021-05-02T08:51:31","slug":"separes-de-moi-vous-ne-pouvez-rien-faire","status":"publish","type":"post","link":"https:\/\/banneux-nd.be\/pl\/separes-de-moi-vous-ne-pouvez-rien-faire\/","title":{"rendered":"S\u00e9par\u00e9s de moi, vous ne pouvez rien faire !"},"content":{"rendered":"\n<h3 style=\"text-align: center;\">Cinqui\u00e8me dimanche du temps pascal B<\/h3>\n<p><strong>Lectures <\/strong>Ac 9, 26-31\u00a0; 1 Jn 3, 18-24\u00a0; Jn 15, 1-8<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0S\u00e9par\u00e9s de moi, vous ne pouvez rien faire\u00a0!\u00a0\u00bb Voil\u00e0 encore une de ces paroles-choc de J\u00e9sus. Il \u00e9voque une d\u00e9pendance totale, alors que nous r\u00eavons sans cesse d\u2019autonomie, voire d\u2019ind\u00e9pendance\u00a0!<\/p>\n<p style=\"text-align: justify;\"><strong>Vive l\u2019autonomie<\/strong><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"wp-image-15421 alignleft lazyload\" data-src=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/05\/2365681.jpg\" alt=\"\" width=\"464\" height=\"261\" data-srcset=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/05\/2365681.jpg 840w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/05\/2365681-300x169.jpg 300w, https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/05\/2365681-768x432.jpg 768w\" data-sizes=\"(max-width: 464px) 100vw, 464px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 464px; --smush-placeholder-aspect-ratio: 464\/261;\" \/>Soulignons d\u2019abord qu\u2019une certaine aspiration \u00e0 l\u2019autonomie est une belle et bonne chose. Je pense \u00e0 des personnes qui souffrent d\u2019un handicap. Il est admirable de voir tout ce qu\u2019on a pu mettre en place pour que beaucoup parmi elles puissent vivre dans leur appartement et jouir d\u2019une relative autonomie. Il en va de m\u00eame pour des personnes \u00e2g\u00e9es. Beaucoup quittent leur maison et sont accueillis dans une r\u00e9sidence-services : elles ont leur studio ou leur appartement, mais peuvent faire appel \u00e0 de l\u2019aide quand cela s\u2019av\u00e8re n\u00e9cessaire. Je suis s\u00fbr que J\u00e9sus applaudit toutes ces initiatives et s\u2019en r\u00e9jouit du fond du c\u0153ur ! D\u2019ailleurs, tout au long de sa vie publique, J\u00e9sus remet l\u2019homme debout et l\u2019invite \u00e0 se mettre en route. Il suffit de penser au paralys\u00e9 \u00e0 qui il donne cet ordre : \u00ab L\u00e8ve-toi, prends ton brancard et rentre chez toi ! \u00bb (Mc 2, 11) L\u2019homme avait d\u00fb faire appel \u00e0 quatre amis brancardiers pour l\u2019amener aupr\u00e8s de J\u00e9sus. Au retour, il peut se servir de ses jambes. Et tous les t\u00e9moins sont \u00ab boulevers\u00e9s et rendent gloire \u00e0 Dieu ! \u00bb Oui, la gloire de Dieu, c\u2019est l\u2019homme debout et vivant !<\/p>\n<p style=\"text-align: justify;\"><strong>Bienheureuse interd\u00e9pendance<\/strong><\/p>\n<p style=\"text-align: justify;\">Mais notre autonomie, notre ind\u00e9pendance est toute relative. Depuis le d\u00e9but, notre pape Fran\u00e7ois rappelle sans cesse qu\u2019il y a une <strong>interd\u00e9pendance<\/strong>. Tout est li\u00e9, tout est reli\u00e9. Nous faisons partie d\u2019un grand ensemble dont nous ne pouvons pas nous extraire. Nous vivons d\u2019\u00e9changes. Avec la nature, avec les autres. Nous sommes essentiellement des \u00eatres de relation, et nous ne pouvons pas nous passer de ces relations. Or, la premi\u00e8re, la plus essentielle des relations est celle qui nous relie \u00e0 Dieu.<\/p>\n<p style=\"text-align: justify;\">L\u2019homme est libre d\u2019ignorer ou de nier ce lien, il existe pourtant. Car Dieu est \u00ab\u00a0le cr\u00e9ateur du ciel et de la terre, de l\u2019univers visible et invisible.\u00a0\u00bb Chaque cr\u00e9ature doit son existence au cr\u00e9ateur, qu\u2019elle le veuille ou non, qu\u2019elle le reconnaisse ou non. Cet acte cr\u00e9ateur n\u2019est pas uniquement l\u2019acte initial, l\u2019acte qui lance la cr\u00e9ature dans l\u2019\u00eatre. Il s\u2019agit d\u2019un acte permanent\u00a0: le Cr\u00e9ateur nous (main)tient dans l\u2019\u00eatre. Paul le dit clairement \u00e0 ses auditeurs \u00e0 Ath\u00e8nes\u00a0: \u00ab\u00a0c\u2019est en lui que nous avons la vie, le mouvement et l\u2019\u00eatre\u00a0\u00bb (Ac 17, 28). Nous sommes en permanence dans la main de Dieu et il nous porte. C\u2019est en ce sens-l\u00e0 que le livre de Tobie peut affirmer\u00a0: \u00ab\u00a0Il n\u2019y a rien qui \u00e9chappe \u00e0 sa main\u00a0\u00bb (13, 2).<\/p>\n<p style=\"text-align: justify;\">Certains chants liturgiques expriment cela avec grande simplicit\u00e9 et beaut\u00e9. Ainsi, un beau chant \u00e0 la Vierge Marie commence par ces mots\u00a0: \u00ab\u00a0Tu as port\u00e9 celui qui porte tout, notre Sauveur en ton sein a pris chair.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\"><strong>Illusions tragiques<\/strong><\/p>\n<p style=\"text-align: justify;\">Nous pouvons r\u00eaver d\u2019une autonomie totale, mais une telle autonomie n\u2019est qu\u2019illusion. Nous faisons partie d\u2019un tout, nous sommes une partie int\u00e9grale de la cr\u00e9ation qui nous porte et nous soutient. Cette d\u00e9pendance de notre environnement nous appara\u00eet de plus en plus clairement. L\u2019homme a besoin de la nature. La nature, par contre, pourrait parfaitement se passer de l\u2019homme. Il en va de m\u00eame de Dieu\u00a0: c\u2019est par bont\u00e9, c\u2019est par pure g\u00e9n\u00e9rosit\u00e9 que le Cr\u00e9ateur a cr\u00e9\u00e9 le monde. Il est vrai qu\u2019il ne nous a pas demand\u00e9 notre avis et notre consentement, mais il esp\u00e8re que nous reconna\u00eetrons qu\u2019il nous a cr\u00e9\u00e9s par amour et pour l\u2019amour.<\/p>\n<p style=\"text-align: justify;\">L\u2019homme peut nier Dieu, mais Dieu ne le niera pas et continuera \u00e0 le porter dans l\u2019existence\u00a0: il fait lever son soleil sur les bons et les m\u00e9chants et tomber la pluie sur les justes et les injustes. Pourtant, le Seigneur esp\u00e8re une r\u00e9ponse d\u2019amour \u00e0 son offre d\u2019amour. Et le v\u00e9ritable amour se vit librement et sans contrainte. Un grand P\u00e8re de l\u2019Eglise, saint Augustin, a formul\u00e9 cela avec une concision admirable\u00a0: \u00ab\u00a0Dieu qui t\u2019a cr\u00e9\u00e9 sans toi, ne te sauvera pas sans toi.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Au fond, dans l\u2019\u00e9vangile d\u2019aujourd\u2019hui, J\u00e9sus nous parle tout d\u2019abord du secret de sa propre vie et de sa propre joie. Son P\u00e8re est le Vivant, et \u00ab\u00a0moi, je vis par le P\u00e8re.\u00a0\u00bb (Jn 6, 57) Et il nous souhaite de rester reli\u00e9 ind\u00e9fectiblement \u00e0 son P\u00e8re en nous raccrochant \u00e0 lui, co\u00fbte que co\u00fbte\u00a0! Alors, nous pourrons partager sa joie de vivre, ici-bas et dans l\u2019\u00e9ternit\u00e9.<\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: right;\">Abb\u00e9 Leo Palm<\/p>\n<hr \/>\n<h4 style=\"text-align: center;\"><strong>Pri\u00e8re universelle<\/strong><\/h4>\n<p style=\"text-align: justify;\"><em>Si vous demeurez en moi et que mes paroles demeurent en vous, demandez tout ce que vous voudrez, et vous l\u2019obtiendrez. <\/em>Forts de cette promesse, pr\u00e9sentons au Seigneur notre pri\u00e8re commune\u00a0:<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Refrain\u00a0:<\/p>\n<ul style=\"text-align: justify;\">\n<li><em>L\u2019Eglise se construisait et elle avan\u00e7ait\u00a0; elle se multipliait avec l\u2019assistance de l\u2019Esprit Saint. <\/em>Seigneur, nous te confions ton Eglise\u00a0: envoie ton Esprit et suscite des disciples et des ap\u00f4tres pour notre temps. Nous t\u2019en prions.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<ul style=\"text-align: justify;\">\n<li><em>Dieu est plus grand que notre c\u0153ur et il conna\u00eet toutes choses.<\/em> Seigneur, nous te confions tous ceux qui ont peur de toi\u00a0: envoie ton Esprit et fais-leur d\u00e9couvrir ta bont\u00e9 et ta mis\u00e9ricorde sans limites. Nous t\u2019en prions.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<ul style=\"text-align: justify;\">\n<li><em>Voici son commandement\u00a0:<\/em> <em>avoir foi en son Fils J\u00e9sus Christ, et nous aimer les uns les autres. <\/em>Seigneur, nous te confions nos communaut\u00e9s chr\u00e9tiennes\u00a0: envoie ton Esprit et fais-nous grandir dans la foi, l\u2019esp\u00e9rance et l\u2019amour. Nous t\u2019en prions.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<ul style=\"text-align: justify;\">\n<li><em>Moi, je suis la vraie vigne, et mon P\u00e8re est le vigneron.<\/em> Seigneur, nous te confions tous les hommes qui vivent sur notre plan\u00e8te terre. Envoie ton Esprit et permets que tous d\u00e9couvrent le P\u00e8re des cieux, vraie source de solidarit\u00e9 et de fraternit\u00e9. Nous t\u2019en prions.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><em>Ton Esprit vient vivifier ton Eglise et pr\u00e9pare le monde \u00e0 accueillir l\u2019Evangile. Nous avons confiance en toi, Seigneur, et nous te b\u00e9nissons pour tous tes bienfaits. Maintenant et dans les si\u00e8cles des si\u00e8cles.<\/em><\/p>\n<hr \/>\n<h4 style=\"text-align: center;\">Un chant<\/h4>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe class=\"youtube-player lazyload\" width=\"758\" height=\"427\" data-src=\"https:\/\/www.youtube.com\/embed\/vI-vSJrF38w?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=pl-PL&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\" src=\"about:blank\" data-load-mode=\"0\"><\/iframe><\/span><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans l\u2019\u00e9vangile d\u2019aujourd\u2019hui, J\u00e9sus nous parle tout d\u2019abord du secret de sa propre vie et de sa propre joie. Son P\u00e8re est le Vivant, et \u00ab\u00a0moi, je vis par le P\u00e8re.\u00a0\u00bb (Jn 6, 57) Et il nous souhaite de rester reli\u00e9 ind\u00e9fectiblement \u00e0 son P\u00e8re en nous raccrochant \u00e0 lui, co\u00fbte que co\u00fbte\u00a0! Alors, nous pourrons partager sa joie de vivre, ici-bas et dans l\u2019\u00e9ternit\u00e9.<\/p>\n","protected":false},"author":10,"featured_media":15421,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[48],"tags":[283,209],"class_list":["post-15409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","tag-5eme-dimanche-de-paques-b","tag-sanctuaire-de-banneux"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e9par\u00e9s de moi, vous ne pouvez rien faire ! - Banneux Notre-Dame<\/title>\n<meta name=\"description\" content=\"Aujourd&#039;hui, J\u00e9sus nous parle tout d\u2019abord du secret de sa propre vie et de sa propre joie! Son P\u00e8re est le Vivant, et \u00ab\u00a0moi, je vis par le P\u00e8re.\u00a0\u00bb All\u00e9luia!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/banneux-nd.be\/pl\/separes-de-moi-vous-ne-pouvez-rien-faire\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e9par\u00e9s de moi, vous ne pouvez rien faire ! - Banneux Notre-Dame\" \/>\n<meta property=\"og:description\" content=\"Aujourd&#039;hui, J\u00e9sus nous parle tout d\u2019abord du secret de sa propre vie et de sa propre joie! Son P\u00e8re est le Vivant, et \u00ab\u00a0moi, je vis par le P\u00e8re.\u00a0\u00bb All\u00e9luia!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/banneux-nd.be\/pl\/separes-de-moi-vous-ne-pouvez-rien-faire\/\" \/>\n<meta property=\"og:site_name\" content=\"Banneux Notre-Dame\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NDBanneux\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-02T08:51:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-02T08:51:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/05\/2365681.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"473\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fabian Delarbre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabian Delarbre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/separes-de-moi-vous-ne-pouvez-rien-faire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/separes-de-moi-vous-ne-pouvez-rien-faire\\\/\"},\"author\":{\"name\":\"Fabian Delarbre\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/#\\\/schema\\\/person\\\/0d1a4402510d5ffa26dcb30a942708b2\"},\"headline\":\"S\u00e9par\u00e9s de moi, vous ne pouvez rien faire !\",\"datePublished\":\"2021-05-02T08:51:29+00:00\",\"dateModified\":\"2021-05-02T08:51:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/separes-de-moi-vous-ne-pouvez-rien-faire\\\/\"},\"wordCount\":1127,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/separes-de-moi-vous-ne-pouvez-rien-faire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/2365681.jpg\",\"keywords\":[\"5\u00e8me dimanche de P\u00e2ques B\",\"Sanctuaire de Banneux\"],\"articleSection\":[\"A la Une\"],\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/separes-de-moi-vous-ne-pouvez-rien-faire\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/separes-de-moi-vous-ne-pouvez-rien-faire\\\/\",\"url\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/separes-de-moi-vous-ne-pouvez-rien-faire\\\/\",\"name\":\"S\u00e9par\u00e9s de moi, vous ne pouvez rien faire ! - Banneux Notre-Dame\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/separes-de-moi-vous-ne-pouvez-rien-faire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/separes-de-moi-vous-ne-pouvez-rien-faire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/2365681.jpg\",\"datePublished\":\"2021-05-02T08:51:29+00:00\",\"dateModified\":\"2021-05-02T08:51:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/#\\\/schema\\\/person\\\/0d1a4402510d5ffa26dcb30a942708b2\"},\"description\":\"Aujourd'hui, J\u00e9sus nous parle tout d\u2019abord du secret de sa propre vie et de sa propre joie! Son P\u00e8re est le Vivant, et \u00ab\u00a0moi, je vis par le P\u00e8re.\u00a0\u00bb All\u00e9luia!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/separes-de-moi-vous-ne-pouvez-rien-faire\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/separes-de-moi-vous-ne-pouvez-rien-faire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/separes-de-moi-vous-ne-pouvez-rien-faire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/2365681.jpg\",\"contentUrl\":\"https:\\\/\\\/banneux-nd.be\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/2365681.jpg\",\"width\":840,\"height\":473},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/separes-de-moi-vous-ne-pouvez-rien-faire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/witamy-w-banneux\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e9par\u00e9s de moi, vous ne pouvez rien faire !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/\",\"name\":\"Banneux Notre-Dame\",\"description\":\"Sanctuaire de la Vierge des Pauvres (Belgique)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/#\\\/schema\\\/person\\\/0d1a4402510d5ffa26dcb30a942708b2\",\"name\":\"Fabian Delarbre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g\",\"caption\":\"Fabian Delarbre\"},\"url\":\"https:\\\/\\\/banneux-nd.be\\\/pl\\\/author\\\/sanctuaire\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e9par\u00e9s de moi, vous ne pouvez rien faire ! - Banneux Notre-Dame","description":"Aujourd'hui, J\u00e9sus nous parle tout d\u2019abord du secret de sa propre vie et de sa propre joie! Son P\u00e8re est le Vivant, et \u00ab\u00a0moi, je vis par le P\u00e8re.\u00a0\u00bb All\u00e9luia!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/banneux-nd.be\/pl\/separes-de-moi-vous-ne-pouvez-rien-faire\/","og_locale":"pl_PL","og_type":"article","og_title":"S\u00e9par\u00e9s de moi, vous ne pouvez rien faire ! - Banneux Notre-Dame","og_description":"Aujourd'hui, J\u00e9sus nous parle tout d\u2019abord du secret de sa propre vie et de sa propre joie! Son P\u00e8re est le Vivant, et \u00ab\u00a0moi, je vis par le P\u00e8re.\u00a0\u00bb All\u00e9luia!","og_url":"https:\/\/banneux-nd.be\/pl\/separes-de-moi-vous-ne-pouvez-rien-faire\/","og_site_name":"Banneux Notre-Dame","article_publisher":"https:\/\/www.facebook.com\/NDBanneux\/","article_published_time":"2021-05-02T08:51:29+00:00","article_modified_time":"2021-05-02T08:51:31+00:00","og_image":[{"width":840,"height":473,"url":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/05\/2365681.jpg","type":"image\/jpeg"}],"author":"Fabian Delarbre","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Fabian Delarbre","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/banneux-nd.be\/pl\/separes-de-moi-vous-ne-pouvez-rien-faire\/#article","isPartOf":{"@id":"https:\/\/banneux-nd.be\/pl\/separes-de-moi-vous-ne-pouvez-rien-faire\/"},"author":{"name":"Fabian Delarbre","@id":"https:\/\/banneux-nd.be\/pl\/#\/schema\/person\/0d1a4402510d5ffa26dcb30a942708b2"},"headline":"S\u00e9par\u00e9s de moi, vous ne pouvez rien faire !","datePublished":"2021-05-02T08:51:29+00:00","dateModified":"2021-05-02T08:51:31+00:00","mainEntityOfPage":{"@id":"https:\/\/banneux-nd.be\/pl\/separes-de-moi-vous-ne-pouvez-rien-faire\/"},"wordCount":1127,"commentCount":0,"image":{"@id":"https:\/\/banneux-nd.be\/pl\/separes-de-moi-vous-ne-pouvez-rien-faire\/#primaryimage"},"thumbnailUrl":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/05\/2365681.jpg","keywords":["5\u00e8me dimanche de P\u00e2ques B","Sanctuaire de Banneux"],"articleSection":["A la Une"],"inLanguage":"pl-PL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/banneux-nd.be\/pl\/separes-de-moi-vous-ne-pouvez-rien-faire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/banneux-nd.be\/pl\/separes-de-moi-vous-ne-pouvez-rien-faire\/","url":"https:\/\/banneux-nd.be\/pl\/separes-de-moi-vous-ne-pouvez-rien-faire\/","name":"S\u00e9par\u00e9s de moi, vous ne pouvez rien faire ! - Banneux Notre-Dame","isPartOf":{"@id":"https:\/\/banneux-nd.be\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/banneux-nd.be\/pl\/separes-de-moi-vous-ne-pouvez-rien-faire\/#primaryimage"},"image":{"@id":"https:\/\/banneux-nd.be\/pl\/separes-de-moi-vous-ne-pouvez-rien-faire\/#primaryimage"},"thumbnailUrl":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/05\/2365681.jpg","datePublished":"2021-05-02T08:51:29+00:00","dateModified":"2021-05-02T08:51:31+00:00","author":{"@id":"https:\/\/banneux-nd.be\/pl\/#\/schema\/person\/0d1a4402510d5ffa26dcb30a942708b2"},"description":"Aujourd'hui, J\u00e9sus nous parle tout d\u2019abord du secret de sa propre vie et de sa propre joie! Son P\u00e8re est le Vivant, et \u00ab\u00a0moi, je vis par le P\u00e8re.\u00a0\u00bb All\u00e9luia!","breadcrumb":{"@id":"https:\/\/banneux-nd.be\/pl\/separes-de-moi-vous-ne-pouvez-rien-faire\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/banneux-nd.be\/pl\/separes-de-moi-vous-ne-pouvez-rien-faire\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/banneux-nd.be\/pl\/separes-de-moi-vous-ne-pouvez-rien-faire\/#primaryimage","url":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/05\/2365681.jpg","contentUrl":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/05\/2365681.jpg","width":840,"height":473},{"@type":"BreadcrumbList","@id":"https:\/\/banneux-nd.be\/pl\/separes-de-moi-vous-ne-pouvez-rien-faire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/banneux-nd.be\/pl\/witamy-w-banneux\/"},{"@type":"ListItem","position":2,"name":"S\u00e9par\u00e9s de moi, vous ne pouvez rien faire !"}]},{"@type":"WebSite","@id":"https:\/\/banneux-nd.be\/pl\/#website","url":"https:\/\/banneux-nd.be\/pl\/","name":"Banneux Notre-Dame","description":"Sanctuaire de la Vierge des Pauvres (Belgique)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/banneux-nd.be\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Person","@id":"https:\/\/banneux-nd.be\/pl\/#\/schema\/person\/0d1a4402510d5ffa26dcb30a942708b2","name":"Fabian Delarbre","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/secure.gravatar.com\/avatar\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9334616c7d1b6f2105ff49faafff30af9ea103fbf51fe51d908b6b0ee326e990?s=96&d=mm&r=g","caption":"Fabian Delarbre"},"url":"https:\/\/banneux-nd.be\/pl\/author\/sanctuaire\/"}]}},"author_meta":{"display_name":"Fabian Delarbre","author_link":"https:\/\/banneux-nd.be\/pl\/author\/sanctuaire\/"},"featured_img":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/05\/2365681-300x169.jpg","jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/banneux-nd.be\/wp-content\/uploads\/2021\/05\/2365681.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/banneux-nd.be\/fr\/category\/a-la-une\/\" class=\"advgb-post-tax-term\">A la Une<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">A la Une<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/banneux-nd.be\/fr\/category\/a-la-une\/\" class=\"advgb-post-tax-term\">5\u00e8me dimanche de P\u00e2ques B<\/a>","<a href=\"https:\/\/banneux-nd.be\/fr\/category\/a-la-une\/\" class=\"advgb-post-tax-term\">Sanctuaire de Banneux<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">5\u00e8me dimanche de P\u00e2ques B<\/span>","<span class=\"advgb-post-tax-term\">Sanctuaire de Banneux<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Opublikowano 5 years temu","modified":"Zaktualizowano 5 years temu"},"absolute_dates":{"created":"Opublikowano 05\/02\/2021","modified":"Zaktualizowano 05\/02\/2021"},"absolute_dates_time":{"created":"Opublikowano 05\/02\/2021 10 h 51 min","modified":"Zaktualizowano 05\/02\/2021 10 h 51 min"},"featured_img_caption":"","series_order":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/banneux-nd.be\/pl\/wp-json\/wp\/v2\/posts\/15409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/banneux-nd.be\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/banneux-nd.be\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/banneux-nd.be\/pl\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/banneux-nd.be\/pl\/wp-json\/wp\/v2\/comments?post=15409"}],"version-history":[{"count":6,"href":"https:\/\/banneux-nd.be\/pl\/wp-json\/wp\/v2\/posts\/15409\/revisions"}],"predecessor-version":[{"id":15429,"href":"https:\/\/banneux-nd.be\/pl\/wp-json\/wp\/v2\/posts\/15409\/revisions\/15429"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/banneux-nd.be\/pl\/wp-json\/wp\/v2\/media\/15421"}],"wp:attachment":[{"href":"https:\/\/banneux-nd.be\/pl\/wp-json\/wp\/v2\/media?parent=15409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/banneux-nd.be\/pl\/wp-json\/wp\/v2\/categories?post=15409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/banneux-nd.be\/pl\/wp-json\/wp\/v2\/tags?post=15409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}